{"id":10182,"date":"2013-01-31T08:45:25","date_gmt":"2013-01-31T08:45:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/Emilio_Locandina.jpg"},"modified":"2013-01-31T08:45:25","modified_gmt":"2013-01-31T08:45:25","slug":"emilio_locandina","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/31\/il-nuovo-film-di-angelo-cretella-con-nandu-popu\/emilio_locandina\/","title":{"rendered":"Emilio_Locandina"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/Emilio_Locandina.jpg'><img width=\"207\" height=\"300\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/Emilio_Locandina-207x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/Emilio_Locandina-207x300.jpg 207w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/Emilio_Locandina.jpg 602w\" sizes=\"(max-width: 207px) 100vw, 207px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/31\/il-nuovo-film-di-angelo-cretella-con-nandu-popu\/emilio_locandina\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/31\/il-nuovo-film-di-angelo-cretella-con-nandu-popu\/emilio_locandina\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"602","height":"869","hwstring_small":"height='96' width='66'","file":"2013\/01\/Emilio_Locandina.jpg","sizes":{"thumbnail":{"file":"Emilio_Locandina-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/Emilio_Locandina-150x150.jpg"},"medium":{"file":"Emilio_Locandina-207x300.jpg","width":"207","height":"300","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/Emilio_Locandina-207x300.jpg"},"full":{"file":"Emilio_Locandina.jpg","width":602,"height":869,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/Emilio_Locandina.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":10181,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/Emilio_Locandina.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10182"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10182"}]}}