{"id":10744,"date":"2013-02-10T10:04:05","date_gmt":"2013-02-10T10:04:05","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/piazzale-delle-foibe21.jpg"},"modified":"2013-02-10T10:04:05","modified_gmt":"2013-02-10T10:04:05","slug":"piazzale-delle-foibe2-2","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/10\/nardo-la-piazza-dedicata-ai-martiri-delle-foibe-nel-degrado\/piazzale-delle-foibe2-2\/","title":{"rendered":"piazzale delle foibe2"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/piazzale-delle-foibe21.jpg'><img width=\"300\" height=\"152\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/piazzale-delle-foibe21-300x152.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/piazzale-delle-foibe21-300x152.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/piazzale-delle-foibe21.jpg 937w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/10\/nardo-la-piazza-dedicata-ai-martiri-delle-foibe-nel-degrado\/piazzale-delle-foibe2-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/10\/nardo-la-piazza-dedicata-ai-martiri-delle-foibe-nel-degrado\/piazzale-delle-foibe2-2\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"937","height":"475","hwstring_small":"height='64' width='128'","file":"2013\/02\/piazzale-delle-foibe21.jpg","sizes":{"thumbnail":{"file":"piazzale-delle-foibe21-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/piazzale-delle-foibe21-150x150.jpg"},"medium":{"file":"piazzale-delle-foibe21-300x152.jpg","width":"300","height":"152","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/piazzale-delle-foibe21-300x152.jpg"},"full":{"file":"piazzale-delle-foibe21.jpg","width":937,"height":475,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/piazzale-delle-foibe21.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":10739,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/piazzale-delle-foibe21.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10744"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10744"}]}}