{"id":11179,"date":"2013-02-17T08:38:31","date_gmt":"2013-02-17T08:38:31","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/manifesto_Dio-come-ti-olio.jpg"},"modified":"2013-02-17T08:38:31","modified_gmt":"2013-02-17T08:38:31","slug":"manifesto_dio-come-ti-olio","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/17\/dio-come-ti-olio\/manifesto_dio-come-ti-olio\/","title":{"rendered":"manifesto_Dio come ti olio"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/manifesto_Dio-come-ti-olio.jpg'><img width=\"212\" height=\"300\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/manifesto_Dio-come-ti-olio-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/manifesto_Dio-come-ti-olio-212x300.jpg 212w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/manifesto_Dio-come-ti-olio.jpg 707w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/17\/dio-come-ti-olio\/manifesto_dio-come-ti-olio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/17\/dio-come-ti-olio\/manifesto_dio-come-ti-olio\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"707","height":"1000","hwstring_small":"height='96' width='67'","file":"2013\/02\/manifesto_Dio-come-ti-olio.jpg","sizes":{"thumbnail":{"file":"manifesto_Dio-come-ti-olio-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/manifesto_Dio-come-ti-olio-150x150.jpg"},"medium":{"file":"manifesto_Dio-come-ti-olio-212x300.jpg","width":"212","height":"300","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/manifesto_Dio-come-ti-olio-212x300.jpg"},"full":{"file":"manifesto_Dio-come-ti-olio.jpg","width":707,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/manifesto_Dio-come-ti-olio.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":11178,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/manifesto_Dio-come-ti-olio.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11179"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11179"}]}}