{"id":11875,"date":"2013-02-28T08:34:24","date_gmt":"2013-02-28T08:34:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320.jpg"},"modified":"2013-02-28T08:34:24","modified_gmt":"2013-02-28T08:34:24","slug":"scuola-di-circo-per-la-befana-0_23430-400x320","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/28\/il-circo-senza-animali\/scuola-di-circo-per-la-befana-0_23430-400x320\/","title":{"rendered":"scuola-di-circo-per-la-befana-0_23430&#8211;400&#215;320"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320.jpg'><img width=\"300\" height=\"240\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320-300x240.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320-300x240.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/28\/il-circo-senza-animali\/scuola-di-circo-per-la-befana-0_23430-400x320\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/28\/il-circo-senza-animali\/scuola-di-circo-per-la-befana-0_23430-400x320\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"400","height":"320","hwstring_small":"height='96' width='120'","file":"2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320.jpg","sizes":{"thumbnail":{"file":"scuola-di-circo-per-la-befana-0_23430-400x320-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320-150x150.jpg"},"medium":{"file":"scuola-di-circo-per-la-befana-0_23430-400x320-300x240.jpg","width":"300","height":"240","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320-300x240.jpg"},"full":{"file":"scuola-di-circo-per-la-befana-0_23430-400x320.jpg","width":400,"height":320,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":11874,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/scuola-di-circo-per-la-befana-0_23430-400x320.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11875"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11875"}]}}