{"id":12211,"date":"2013-03-04T21:03:52","date_gmt":"2013-03-04T21:03:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/alfredo-pagliaro1.jpg"},"modified":"2013-03-04T21:03:52","modified_gmt":"2013-03-04T21:03:52","slug":"alfredo-pagliaro-2","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/04\/conferenza-dei-consigli-comunali-dellanci\/alfredo-pagliaro-2\/","title":{"rendered":"alfredo pagliaro"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/alfredo-pagliaro1.jpg'><img width=\"201\" height=\"217\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/alfredo-pagliaro1.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/04\/conferenza-dei-consigli-comunali-dellanci\/alfredo-pagliaro-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/04\/conferenza-dei-consigli-comunali-dellanci\/alfredo-pagliaro-2\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"201","height":"217","hwstring_small":"height='96' width='88'","file":"2013\/03\/alfredo-pagliaro1.jpg","sizes":{"thumbnail":{"file":"alfredo-pagliaro1-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/alfredo-pagliaro1-150x150.jpg"},"full":{"file":"alfredo-pagliaro1.jpg","width":201,"height":217,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/alfredo-pagliaro1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":12209,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/alfredo-pagliaro1.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/12211"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12211"}]}}