{"id":12358,"date":"2013-03-08T08:38:44","date_gmt":"2013-03-08T08:38:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Antonio-Rosario-Fanelli.jpg"},"modified":"2013-03-08T08:38:44","modified_gmt":"2013-03-08T08:38:44","slug":"antonio-rosario-fanelli","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/la-puglia-il-manierismo-la-controriforma\/antonio-rosario-fanelli\/","title":{"rendered":"Antonio Rosario Fanelli"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Antonio-Rosario-Fanelli.jpg'>Antonio Rosario Fanelli<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/la-puglia-il-manierismo-la-controriforma\/antonio-rosario-fanelli\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/la-puglia-il-manierismo-la-controriforma\/antonio-rosario-fanelli\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":"<p>Antonio Rosario Fanelli<\/p>\n"},"alt_text":"","media_type":"file","mime_type":"image\/jpeg","media_details":{},"post":12357,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Antonio-Rosario-Fanelli.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/12358"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12358"}]}}