{"id":12390,"date":"2013-03-08T09:04:11","date_gmt":"2013-03-08T09:04:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Simone-Perrone-live_10-marzo-013_locandina.jpg"},"modified":"2013-03-08T09:04:11","modified_gmt":"2013-03-08T09:04:11","slug":"simone-perrone-live_10-marzo-013_locandina","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/per-le-serate-live-del-coffee-and-cigarettes-di-lecce\/simone-perrone-live_10-marzo-013_locandina\/","title":{"rendered":"Simone Perrone live_10 marzo 013_locandina"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Simone-Perrone-live_10-marzo-013_locandina.jpg'><img width=\"223\" height=\"300\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Simone-Perrone-live_10-marzo-013_locandina-223x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Simone-Perrone-live_10-marzo-013_locandina-223x300.jpg 223w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Simone-Perrone-live_10-marzo-013_locandina.jpg 667w\" sizes=\"(max-width: 223px) 100vw, 223px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/per-le-serate-live-del-coffee-and-cigarettes-di-lecce\/simone-perrone-live_10-marzo-013_locandina\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/08\/per-le-serate-live-del-coffee-and-cigarettes-di-lecce\/simone-perrone-live_10-marzo-013_locandina\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"667","height":"896","hwstring_small":"height='96' width='71'","file":"2013\/03\/Simone-Perrone-live_10-marzo-013_locandina.jpg","sizes":{"thumbnail":{"file":"Simone-Perrone-live_10-marzo-013_locandina-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Simone-Perrone-live_10-marzo-013_locandina-150x150.jpg"},"medium":{"file":"Simone-Perrone-live_10-marzo-013_locandina-223x300.jpg","width":"223","height":"300","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Simone-Perrone-live_10-marzo-013_locandina-223x300.jpg"},"full":{"file":"Simone-Perrone-live_10-marzo-013_locandina.jpg","width":667,"height":896,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Simone-Perrone-live_10-marzo-013_locandina.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":12389,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Simone-Perrone-live_10-marzo-013_locandina.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/12390"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12390"}]}}