{"id":12514,"date":"2013-03-10T15:03:06","date_gmt":"2013-03-10T15:03:06","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/indiano-a-cavallo.jpg"},"modified":"2013-03-10T15:03:06","modified_gmt":"2013-03-10T15:03:06","slug":"indiano-a-cavallo","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/10\/lecce-un-indiano-si-reca-in-questura-e-ci-rimette-le-penne\/indiano-a-cavallo\/","title":{"rendered":"indiano a cavallo"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/indiano-a-cavallo.jpg'><img width=\"300\" height=\"279\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/indiano-a-cavallo-300x279.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/indiano-a-cavallo-300x279.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/indiano-a-cavallo.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/10\/lecce-un-indiano-si-reca-in-questura-e-ci-rimette-le-penne\/indiano-a-cavallo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/10\/lecce-un-indiano-si-reca-in-questura-e-ci-rimette-le-penne\/indiano-a-cavallo\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1000","height":"933","hwstring_small":"height='96' width='102'","file":"2013\/03\/indiano-a-cavallo.jpg","sizes":{"thumbnail":{"file":"indiano-a-cavallo-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/indiano-a-cavallo-150x150.jpg"},"medium":{"file":"indiano-a-cavallo-300x279.jpg","width":"300","height":"279","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/indiano-a-cavallo-300x279.jpg"},"full":{"file":"indiano-a-cavallo.jpg","width":1000,"height":933,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/indiano-a-cavallo.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":12513,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/indiano-a-cavallo.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/12514"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=12514"}]}}