{"id":13165,"date":"2013-03-21T08:12:04","date_gmt":"2013-03-21T08:12:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Locandina-Cuore-di-Donna.jpg"},"modified":"2013-03-21T08:12:04","modified_gmt":"2013-03-21T08:12:04","slug":"locandina-cuore-di-donna","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/cuore-di-donna-serata-dedicata-alla-lilt\/locandina-cuore-di-donna\/","title":{"rendered":"Locandina Cuore di Donna"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Locandina-Cuore-di-Donna.jpg'><img width=\"180\" height=\"300\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Locandina-Cuore-di-Donna-180x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Locandina-Cuore-di-Donna-180x300.jpg 180w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Locandina-Cuore-di-Donna.jpg 600w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/cuore-di-donna-serata-dedicata-alla-lilt\/locandina-cuore-di-donna\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/cuore-di-donna-serata-dedicata-alla-lilt\/locandina-cuore-di-donna\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"600","height":"1000","hwstring_small":"height='96' width='57'","file":"2013\/03\/Locandina-Cuore-di-Donna.jpg","sizes":{"thumbnail":{"file":"Locandina-Cuore-di-Donna-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Locandina-Cuore-di-Donna-150x150.jpg"},"medium":{"file":"Locandina-Cuore-di-Donna-180x300.jpg","width":"180","height":"300","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Locandina-Cuore-di-Donna-180x300.jpg"},"full":{"file":"Locandina-Cuore-di-Donna.jpg","width":600,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Locandina-Cuore-di-Donna.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":13164,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Locandina-Cuore-di-Donna.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13165"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13165"}]}}