{"id":13492,"date":"2013-03-27T11:13:18","date_gmt":"2013-03-27T11:13:18","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones.jpg"},"modified":"2013-03-27T11:13:18","modified_gmt":"2013-03-27T11:13:18","slug":"foto-ramones","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/radio-ramones-rivivere-il-punk-rock-newyorkese-al-black-betty-di-lecce\/foto-ramones\/","title":{"rendered":"Foto Ramones"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/radio-ramones-rivivere-il-punk-rock-newyorkese-al-black-betty-di-lecce\/foto-ramones\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/radio-ramones-rivivere-il-punk-rock-newyorkese-al-black-betty-di-lecce\/foto-ramones\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"600","height":"600","hwstring_small":"height='96' width='96'","file":"2013\/03\/Foto-Ramones.jpg","sizes":{"thumbnail":{"file":"Foto-Ramones-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones-150x150.jpg"},"medium":{"file":"Foto-Ramones-300x300.jpg","width":"300","height":"300","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones-300x300.jpg"},"full":{"file":"Foto-Ramones.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":13491,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Foto-Ramones.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13492"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13492"}]}}