{"id":14065,"date":"2013-04-09T15:59:54","date_gmt":"2013-04-09T15:59:54","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001.jpg"},"modified":"2013-04-09T15:59:54","modified_gmt":"2013-04-09T15:59:54","slug":"20120415_elly_model_001","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/09\/le-amiche-di-leccecronaca-it-elly-tutto-con-passione\/20120415_elly_model_001\/","title":{"rendered":"20120415_Elly_Model_001"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001.jpg'><img width=\"200\" height=\"300\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001-200x300.jpg 200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001-682x1024.jpg 682w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/09\/le-amiche-di-leccecronaca-it-elly-tutto-con-passione\/20120415_elly_model_001\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/09\/le-amiche-di-leccecronaca-it-elly-tutto-con-passione\/20120415_elly_model_001\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1200","height":"1800","hwstring_small":"height='96' width='64'","file":"2013\/04\/20120415_Elly_Model_001.jpg","sizes":{"thumbnail":{"file":"20120415_Elly_Model_001-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001-150x150.jpg"},"medium":{"file":"20120415_Elly_Model_001-200x300.jpg","width":"200","height":"300","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001-200x300.jpg"},"large":{"file":"20120415_Elly_Model_001-682x1024.jpg","width":"682","height":"1024","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001-682x1024.jpg"},"full":{"file":"20120415_Elly_Model_001.jpg","width":1200,"height":1800,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1334503490","copyright":"http:\/\/www.gruener-fotodesign.de","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":14061,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/20120415_Elly_Model_001.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/14065"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=14065"}]}}