{"id":14950,"date":"2013-04-23T15:39:10","date_gmt":"2013-04-23T15:39:10","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage.jpg"},"modified":"2013-04-23T15:39:10","modified_gmt":"2013-04-23T15:39:10","slug":"caritas-e-il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/casa-della-carita-porte-aperte-ai-bisognosi\/caritas-e-il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage\/","title":{"rendered":"Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage.jpg'><img width=\"300\" height=\"199\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage.jpg 770w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/casa-della-carita-porte-aperte-ai-bisognosi\/caritas-e-il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/casa-della-carita-porte-aperte-ai-bisognosi\/caritas-e-il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"770","height":"512","hwstring_small":"height='85' width='128'","file":"2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage.jpg","sizes":{"thumbnail":{"file":"Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage-150x150.jpg"},"medium":{"file":"Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage-300x199.jpg","width":"300","height":"199","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage-300x199.jpg"},"full":{"file":"Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage.jpg","width":770,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":14949,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Caritas-e-Il-cuore-si-scioglie-alleanza-contro-la-poverta_articleimage.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/14950"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=14950"}]}}