{"id":19840,"date":"2013-08-31T07:27:45","date_gmt":"2013-08-31T07:27:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5.jpg"},"modified":"2013-08-31T07:27:45","modified_gmt":"2013-08-31T07:27:45","slug":"via-imp-adriano-aiuole-5","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/via-imp-adriano-aiuole-5\/","title":{"rendered":"via Imp Adriano aiuole 5"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5.jpg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5.jpg 648w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/via-imp-adriano-aiuole-5\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/via-imp-adriano-aiuole-5\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"648","height":"486","hwstring_small":"height='96' width='128'","file":"2013\/08\/via-Imp-Adriano-aiuole-5.jpg","sizes":{"thumbnail":{"file":"via-Imp-Adriano-aiuole-5-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5-150x150.jpg"},"medium":{"file":"via-Imp-Adriano-aiuole-5-300x225.jpg","width":"300","height":"225","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5-300x225.jpg"},"full":{"file":"via-Imp-Adriano-aiuole-5.jpg","width":648,"height":486,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":19835,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19840"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19840"}]}}