{"id":21815,"date":"2013-11-12T17:21:59","date_gmt":"2013-11-12T17:21:59","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/lodi-10.png"},"modified":"2013-11-12T17:21:59","modified_gmt":"2013-11-12T17:21:59","slug":"lodi-10","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/12\/posano-nude-per-la-citta-con-la-benedizione-del-sindaco-in-allegato-la-galleria-con-le-foto\/lodi-10\/","title":{"rendered":"lodi 10"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/lodi-10.png'><img width=\"300\" height=\"222\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/lodi-10-300x222.png\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/lodi-10-300x222.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/lodi-10.png 583w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/12\/posano-nude-per-la-citta-con-la-benedizione-del-sindaco-in-allegato-la-galleria-con-le-foto\/lodi-10\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/12\/posano-nude-per-la-citta-con-la-benedizione-del-sindaco-in-allegato-la-galleria-con-le-foto\/lodi-10\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":"583","height":"433","hwstring_small":"height='96' width='128'","file":"2013\/11\/lodi-10.png","sizes":{"thumbnail":{"file":"lodi-10-150x150.png","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/lodi-10-150x150.png"},"medium":{"file":"lodi-10-300x222.png","width":"300","height":"222","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/lodi-10-300x222.png"},"full":{"file":"lodi-10.png","width":583,"height":433,"mime_type":"image\/png","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/lodi-10.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":21808,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/lodi-10.png","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21815"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21815"}]}}