{"id":21886,"date":"2013-11-13T16:38:29","date_gmt":"2013-11-13T16:38:29","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla.jpg"},"modified":"2013-11-13T16:38:29","modified_gmt":"2013-11-13T16:38:29","slug":"cataldo-motta-alla-conferenza-stampa-sulle-nuove-indagini-a-francavilla","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/13\/cataldo-motta-ospite-del-liceo-scientifico-leonardo-da-vinci-di-maglie\/cataldo-motta-alla-conferenza-stampa-sulle-nuove-indagini-a-francavilla\/","title":{"rendered":"Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla.jpg'><img width=\"300\" height=\"199\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla-1024x680.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla.jpg 1695w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/13\/cataldo-motta-ospite-del-liceo-scientifico-leonardo-da-vinci-di-maglie\/cataldo-motta-alla-conferenza-stampa-sulle-nuove-indagini-a-francavilla\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/13\/cataldo-motta-ospite-del-liceo-scientifico-leonardo-da-vinci-di-maglie\/cataldo-motta-alla-conferenza-stampa-sulle-nuove-indagini-a-francavilla\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1695","height":"1126","hwstring_small":"height='85' width='128'","file":"2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla.jpg","sizes":{"thumbnail":{"file":"Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla-150x150.jpg"},"medium":{"file":"Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla-300x199.jpg","width":"300","height":"199","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla-300x199.jpg"},"large":{"file":"Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla-1024x680.jpg","width":"1024","height":"680","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla-1024x680.jpg"},"full":{"file":"Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla.jpg","width":1695,"height":1126,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":21885,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/11\/Cataldo-Motta-alla-conferenza-stampa-sulle-nuove-indagini-a-Francavilla.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/21886"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=21886"}]}}