{"id":23781,"date":"2014-01-22T16:53:24","date_gmt":"2014-01-22T16:53:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/capolupo1.jpg"},"modified":"2014-01-22T16:53:24","modified_gmt":"2014-01-22T16:53:24","slug":"capolupo1","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/22\/il-comandante-generale-della-guardia-di-finanza-generale-di-corpo-darmata-saverio-capolupo-in-visita-alle-fiamme-gialle-della-puglia\/capolupo1\/","title":{"rendered":"capolupo generale finanza"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/capolupo1.jpg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/capolupo1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/capolupo1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/capolupo1.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/22\/il-comandante-generale-della-guardia-di-finanza-generale-di-corpo-darmata-saverio-capolupo-in-visita-alle-fiamme-gialle-della-puglia\/capolupo1\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/01\/22\/il-comandante-generale-della-guardia-di-finanza-generale-di-corpo-darmata-saverio-capolupo-in-visita-alle-fiamme-gialle-della-puglia\/capolupo1\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"400","height":"300","hwstring_small":"height='96' width='128'","file":"2014\/01\/capolupo1.jpg","sizes":{"thumbnail":{"file":"capolupo1-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/capolupo1-150x150.jpg"},"medium":{"file":"capolupo1-300x225.jpg","width":"300","height":"225","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/capolupo1-300x225.jpg"},"full":{"file":"capolupo1.jpg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/capolupo1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":23780,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/01\/capolupo1.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/23781"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23781"}]}}