{"id":2674,"date":"2012-07-10T10:40:31","date_gmt":"2012-07-10T10:40:31","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/pace_1.png.jpeg"},"modified":"2012-07-10T10:40:31","modified_gmt":"2012-07-10T10:40:31","slug":"pace_1-png","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/10\/guerra-e-pace-ancora-sul-costruire-la-cultura-della-pace-dopo-la-morte-di-manuele-braj-e-le-riflessioni-della-nostra-community-avviate-il-28-giugno-scorso-con-lar\/pace_1-png\/","title":{"rendered":"pace_1.png"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/pace_1.png.jpeg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/pace_1.png-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/pace_1.png-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/pace_1.png.jpeg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/10\/guerra-e-pace-ancora-sul-costruire-la-cultura-della-pace-dopo-la-morte-di-manuele-braj-e-le-riflessioni-della-nostra-community-avviate-il-28-giugno-scorso-con-lar\/pace_1-png\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/07\/10\/guerra-e-pace-ancora-sul-costruire-la-cultura-della-pace-dopo-la-morte-di-manuele-braj-e-le-riflessioni-della-nostra-community-avviate-il-28-giugno-scorso-con-lar\/pace_1-png\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"800","height":"600","hwstring_small":"height='96' width='128'","file":"2012\/07\/pace_1.png.jpeg","sizes":{"thumbnail":{"file":"pace_1.png-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/pace_1.png-150x150.jpg"},"medium":{"file":"pace_1.png-300x225.jpg","width":"300","height":"225","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/pace_1.png-300x225.jpg"},"full":{"file":"pace_1.png.jpeg","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/pace_1.png.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":2670,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/07\/pace_1.png.jpeg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/2674"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=2674"}]}}