{"id":27922,"date":"2014-04-22T20:44:41","date_gmt":"2014-04-22T18:44:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro.jpg"},"modified":"2014-04-22T20:44:41","modified_gmt":"2014-04-22T18:44:41","slug":"chiostro","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/dal-monastero-dei-frati-francescani-conventuali-alla-casa-della-convivialita-don-tonino-bello\/chiostro\/","title":{"rendered":"chiostro"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro.jpg'><img width=\"225\" height=\"300\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro.jpg 750w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/dal-monastero-dei-frati-francescani-conventuali-alla-casa-della-convivialita-don-tonino-bello\/chiostro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/04\/22\/dal-monastero-dei-frati-francescani-conventuali-alla-casa-della-convivialita-don-tonino-bello\/chiostro\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"750","height":"1000","hwstring_small":"height='96' width='72'","file":"2014\/04\/chiostro.jpg","sizes":{"thumbnail":{"file":"chiostro-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro-150x150.jpg"},"medium":{"file":"chiostro-225x300.jpg","width":"225","height":"300","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro-225x300.jpg"},"full":{"file":"chiostro.jpg","width":750,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":27920,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/04\/chiostro.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/27922"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=27922"}]}}