{"id":30670,"date":"2014-06-14T09:45:27","date_gmt":"2014-06-14T07:45:27","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi.jpg"},"modified":"2014-06-14T09:45:27","modified_gmt":"2014-06-14T07:45:27","slug":"carta-polmone-maschi-3","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/14\/il-dottor-serravezza-ci-invia-le-tabelle-sui-tumori-nel-salento\/carta-polmone-maschi-3\/","title":{"rendered":"carta polmone maschi"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi.jpg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/14\/il-dottor-serravezza-ci-invia-le-tabelle-sui-tumori-nel-salento\/carta-polmone-maschi-3\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/06\/14\/il-dottor-serravezza-ci-invia-le-tabelle-sui-tumori-nel-salento\/carta-polmone-maschi-3\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1200","height":"901","hwstring_small":"height='96' width='128'","file":"2014\/06\/carta-vescica-maschi.jpg","sizes":{"thumbnail":{"file":"carta-vescica-maschi-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi-150x150.jpg"},"medium":{"file":"carta-vescica-maschi-300x225.jpg","width":"300","height":"225","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi-300x225.jpg"},"large":{"file":"carta-vescica-maschi-1024x768.jpg","width":"1024","height":"768","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi-1024x768.jpg"},"full":{"file":"carta-vescica-maschi.jpg","width":1200,"height":901,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi.jpg"}},"image_meta":{"aperture":"0","credit":"Utente","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"carta polmone maschi"}},"post":30667,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/06\/carta-vescica-maschi.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/30670"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=30670"}]}}