{"id":3430,"date":"2012-08-17T11:44:49","date_gmt":"2012-08-17T11:44:49","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/Opera-di-Carlo-Cofano.jpg"},"modified":"2012-08-17T11:44:49","modified_gmt":"2012-08-17T11:44:49","slug":"opera-di-carlo-cofano","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/17\/aspetti-della-pittura-un-progetto-itinerante-nato-a-lecce\/opera-di-carlo-cofano\/","title":{"rendered":"Opera di Carlo Cofano"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/Opera-di-Carlo-Cofano.jpg'><img width=\"300\" height=\"214\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/Opera-di-Carlo-Cofano-300x214.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/Opera-di-Carlo-Cofano-300x214.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/Opera-di-Carlo-Cofano.jpg 671w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/17\/aspetti-della-pittura-un-progetto-itinerante-nato-a-lecce\/opera-di-carlo-cofano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/08\/17\/aspetti-della-pittura-un-progetto-itinerante-nato-a-lecce\/opera-di-carlo-cofano\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"671","height":"479","hwstring_small":"height='91' width='128'","file":"2012\/08\/Opera-di-Carlo-Cofano.jpg","sizes":{"thumbnail":{"file":"Opera-di-Carlo-Cofano-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/Opera-di-Carlo-Cofano-150x150.jpg"},"medium":{"file":"Opera-di-Carlo-Cofano-300x214.jpg","width":"300","height":"214","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/Opera-di-Carlo-Cofano-300x214.jpg"},"full":{"file":"Opera-di-Carlo-Cofano.jpg","width":671,"height":479,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/Opera-di-Carlo-Cofano.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":3428,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/08\/Opera-di-Carlo-Cofano.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/3430"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=3430"}]}}