{"id":40239,"date":"2014-12-02T16:18:27","date_gmt":"2014-12-02T15:18:27","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05.jpg"},"modified":"2014-12-02T16:18:27","modified_gmt":"2014-12-02T15:18:27","slug":"provincia-ingresso05","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/02\/gli-uffici-della-provincia-di-lecce-sono-un-dormitorio\/provincia-ingresso05\/","title":{"rendered":"provincia ingresso05"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05.jpg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/02\/gli-uffici-della-provincia-di-lecce-sono-un-dormitorio\/provincia-ingresso05\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/12\/02\/gli-uffici-della-provincia-di-lecce-sono-un-dormitorio\/provincia-ingresso05\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1500","height":"1125","hwstring_small":"height='96' width='128'","file":"2014\/12\/provincia-ingresso05.jpg","sizes":{"thumbnail":{"file":"provincia-ingresso05-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05-150x150.jpg"},"medium":{"file":"provincia-ingresso05-300x225.jpg","width":"300","height":"225","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05-300x225.jpg"},"large":{"file":"provincia-ingresso05-1024x768.jpg","width":"1024","height":"768","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05-1024x768.jpg"},"full":{"file":"provincia-ingresso05.jpg","width":1500,"height":1125,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":40237,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/12\/provincia-ingresso05.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/40239"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=40239"}]}}