{"id":5901,"date":"2012-11-11T00:33:23","date_gmt":"2012-11-11T00:33:23","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/loc-francesco-stampa-ok.jpg"},"modified":"2012-11-11T00:33:23","modified_gmt":"2012-11-11T00:33:23","slug":"locandina-francesco","status":"inherit","type":"attachment","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/11\/la-mostra-dellartista-francesco-spagnolo-dal-titolo-111176\/locandina-francesco\/","title":{"rendered":"locandina francesco"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/loc-francesco-stampa-ok.jpg'><img width=\"216\" height=\"300\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/loc-francesco-stampa-ok-216x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/loc-francesco-stampa-ok-216x300.jpg 216w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/loc-francesco-stampa-ok.jpg 722w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/><\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/11\/la-mostra-dellartista-francesco-spagnolo-dal-titolo-111176\/locandina-francesco\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/11\/11\/la-mostra-dellartista-francesco-spagnolo-dal-titolo-111176\/locandina-francesco\/\" layout=\"button_count\"><\/fb:like><\/span>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"722","height":"1000","hwstring_small":"height='96' width='69'","file":"2012\/11\/loc-francesco-stampa-ok.jpg","sizes":{"thumbnail":{"file":"loc-francesco-stampa-ok-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/loc-francesco-stampa-ok-150x150.jpg"},"medium":{"file":"loc-francesco-stampa-ok-216x300.jpg","width":"216","height":"300","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/loc-francesco-stampa-ok-216x300.jpg"},"full":{"file":"loc-francesco-stampa-ok.jpg","width":722,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/loc-francesco-stampa-ok.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"locandina francesco"}},"post":5900,"source_url":"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/loc-francesco-stampa-ok.jpg","_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/5901"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=5901"}]}}