{"id":100649,"date":"2025-10-21T00:01:00","date_gmt":"2025-10-20T22:01:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=100649"},"modified":"2025-10-20T12:36:52","modified_gmt":"2025-10-20T10:36:52","slug":"buongiorno-per-tutto-il-giorno-315","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/21\/buongiorno-per-tutto-il-giorno-315\/","title":{"rendered":"DIARIO DEL GIORNO \/ MARTEDI&#8217; 21 OTTOBRE 2025"},"content":{"rendered":"<p>Buongiorno!<\/p>\n<p>Oggi \u00e8 marted\u00ec 21 ottobre 2025.<\/p>\n<p>Sant&#8217;Orsola.<\/p>\n<p>A Ruffano la scrittrice Alessandra Politi compie 53 anni: auguri di buon compleanno!<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-100655\" title=\"Orsola\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/Orsola-185x300.jpg\" alt=\"\" width=\"185\" height=\"300\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/Orsola-185x300.jpg 185w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/Orsola.jpg 225w\" sizes=\"(max-width: 185px) 100vw, 185px\" \/>Sant&#8217;Orsola, vissuta tra il IV e il V secolo, \u00e8 una santa della Chiesa cattolica. Figlia di un sovrano bretone e giovane di eccezionale bellezza venne promessa in sposa ad un principe pagano, ma, essendosi segretamente consegnata a Dio, chiese di poter rimandare la decisione nella speranza di una conversione da parte del futuro marito.<\/p>\n<p>Poco prima delle nozze decise di partire insieme ad undicimila vergini e dall&#8217;Inghilterra attravers\u00f2 la Manica, il Reno, giunse a Colonia e poi prosegu\u00ec fino a Basilea ed infine a Roma dove venne accolta dal Papa. Successivamente ritorn\u00f2 in patria seguendo la stessa via del viaggio d&#8217;andata. Giunta a Colonia insieme alle undicimila vergini vi trov\u00f2 Attila che aveva occupato la citt\u00e0. Le vergini vennero trucidate e solo lei venne risparmiata poich\u00e9 Attila ne aveva notato la straordinaria bellezza. Ma al rifiuto di Orsola di sposare Attila questi la fece uccidere a colpi di freccia.<\/p>\n<p>Da questo pomeriggio siamo in Luna Nuova.<\/p>\n<p>Questa fase \u00e8 un momento di passaggio e grande trasformazione, caratterizzato da una forte energia rinnovatrice.<\/p>\n<p>Ad esempio, chi digiuna in luna nuova, previene molte malattie poich\u00e9 il corpo ha una maggiore capacit\u00e0 di disintossicarsi; \u00e8 il giorno pi\u00f9 propizio per liberarsi dalle cattive abitudini; alberi malati, dopo la potatura (che deve avvenire in luna calante), possono guarire.<br \/>\nLo stesso tipo di energie della luna nuova si possono ritrovare nella donna nei giorni di flusso mestruale: sono giorni di rilascio di energie e trasformazione, in cui l\u2019energia fisica e quella mentale sono al minimo, affiorano le emozioni e l\u2019estrema sensibilit\u00e0 che caratterizza questi giorni \u00a0pu\u00f2 rendere il mondo esterno troppo pesante da affrontare.<\/p>\n<p>21 ottobre 2001\u00a0\u2013 Viene presentato il primo\u00a0iPod.<\/p>\n<p>21 ottobre 2010\u00a0\u2013 La\u00a0Birmania\u00a0viene denominata ufficialmente\u00a0Repubblica dell&#8217;Unione di Myanmar.<\/p>\n<p>Proverbio salentino: <strong>UARDATE TE LI PEZZENTI RICCUTI<\/strong><br \/>\nGuardati dai pezzenti arricchiti.<br \/>\nPerch\u00e9 guardano con disprezzo ci\u00f2 che erano un tempo, quello che non vogliono tornare ad essere e, a torto, credono che disprezzando i miseri riescano a scongiurare questa possibilit\u00e0.<br \/>\nQuesto proverbio mi ricorda il periodo in cui \u00a0trascorsi qualche anno al Nord, la maggiore ostilit\u00e0 la incontrai proprio in quei meridionali che qualche anno prima si erano trasferiti al Nord.<br \/>\nCostoro nel tentativo di far dimenticare le proprie origini la prima cosa che fanno \u00e8 quella di tentare di parlare come la gente della nuova comunit\u00e0 dove si sono insediati, dando origine a quegli strani idiomi con i quali \u00a0l&#8217;attore Abatantuono ci divert\u00ec nei suoi film di qualche anno fa.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/21\/buongiorno-per-tutto-il-giorno-315\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/21\/buongiorno-per-tutto-il-giorno-315\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Buongiorno! Oggi \u00e8 marted\u00ec 21 ottobre 2025. Sant&#8217;Orsola. A Ruffano la scrittrice Alessandra Politi compie 53 anni: auguri di buon compleanno! Sant&#8217;Orsola, vissuta tra il IV e il V secolo, \u00e8 una santa della Chiesa cattolica. Figlia di un sovrano bretone e giovane di eccezionale bellezza venne promessa in sposa ad un principe pagano, ma, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":100655,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/100649"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=100649"}],"version-history":[{"count":15,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/100649\/revisions"}],"predecessor-version":[{"id":250385,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/100649\/revisions\/250385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/100655"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=100649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=100649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=100649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}