{"id":10113,"date":"2013-01-30T07:56:42","date_gmt":"2013-01-30T07:56:42","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10113"},"modified":"2013-01-30T07:56:42","modified_gmt":"2013-01-30T07:56:42","slug":"un-volume-sui-giganti-verdi-del-salento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/30\/un-volume-sui-giganti-verdi-del-salento\/","title":{"rendered":"UN VOLUME SUI \u201cGIGANTI VERDI\u201d DEL SALENTO"},"content":{"rendered":"<p><strong>\u201cTitani &#8211; Olivi monumentali del Salento\u201d<\/strong> \u00e8 il titolo del volume di <strong>Roberto Gennaio<\/strong>, edizioni Grifo, che verr\u00e0 presentato <span style=\"text-decoration: underline\">domani, mercoled\u00ec 30 gennaio, ore 18, a Palazzo Rovito a Ugento.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019autore accompagna il lettore, attraverso bellissime fotografie, in un percorso affascinante nel mondo dei \u201cgiganti verdi\u201d del territorio salentino, interrogandosi sul futuro che li attende.<\/p>\n<p>&nbsp;<\/p>\n<p>Interverranno <strong>Francesco Pacella,<\/strong> assessore alle Risorse agricole della Provincia di Lecce, <strong>Massimo Lecci<\/strong>, sindaco di Ugento,<strong> Piero Medagli<\/strong>, del Laboratorio di Botanica Sistematica del Disteba dell\u2019Universit\u00e0 del Salento, <strong>Michele Mainardi<\/strong>, docente di Geografia e <strong>Roberto Gennaio<\/strong>, autore del volume. A moderare sar\u00e0 <strong>Giuseppe Pascali<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019incontro \u00e8 patrocinato dalla Provincia (assessorato alle Risorse Agricole) e dal Comune di Ugento.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/10\/convegno-sul-paesaggio-mercoledi-a-castrignano\/ulivo-del-salento-2\/\" rel=\"attachment wp-att-8371\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/ulivo-del-salento.jpg\" alt=\"\" width=\"667\" height=\"1000\" class=\"alignleft size-full wp-image-8371\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/ulivo-del-salento.jpg 667w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/ulivo-del-salento-200x300.jpg 200w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/a>\u201cQuesto volume, attraverso il racconto per immagini, offre un Salento meraviglioso e incantevole grazie alla sua innata vocazione olivicola\u201d, dichiara l\u2019assessore alle Risorse agricole della Provincia di Lecce <strong>Francesco Pacella<\/strong>. \u201cL\u2019albero di olivo \u00e8 uno dei simboli per eccellenza del Salento: ne sono stimati circa 50-60 milioni su tutto il territorio e molti di essi sono secolari\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>E aggiunge: \u201cQuesta pubblicazione rappresenta un tassello importante nella costruzione dei valori condivisi della memoria che l\u2019olivicoltura custodisce nel tempo e nello spazio. E\u2019 perch\u00e9 sono convinto che il mantenimento degli olivi secolari, ambasciatori di presenze storiche millenarie, le importanti funzioni agroalimentari, l\u2019innegabile valenza estetica, nonch\u00e9 il ruolo crescente di fenomeni quali il turismo rurale, il turismo gastronomico e l\u2019interesse per la qualit\u00e0 della vita, trovano riscontro non solo nell\u2019attenzione del coltivatore verso tale tipo di coltura, ma anche nel crescente interesse della popolazione che intende riallacciare i legami con la terra. Tale fenomeno dimostra come la conservazione, in realt\u00e0, non si contrappone allo sviluppo, ma costituisce uno dei nuovi volti dell\u2019innovazione, favorendo un arricchimento continuo del patrimonio di valori della collettivit\u00e0\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cSono grato all\u2019autore per avere scelto di valorizzare lo stretto legame tra il sistema produttivo e paesaggistico dell\u2019olivicoltura e il ruolo storico e anche religioso dell\u2019olivo e dell\u2019olio\u201d, conclude l\u2019assessore <strong>Francesco Pacella.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/30\/un-volume-sui-giganti-verdi-del-salento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/30\/un-volume-sui-giganti-verdi-del-salento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u201cTitani &#8211; Olivi monumentali del Salento\u201d \u00e8 il titolo del volume di Roberto Gennaio, edizioni Grifo, che verr\u00e0 presentato domani, mercoled\u00ec 30 gennaio, ore 18, a Palazzo Rovito a Ugento. &nbsp; L\u2019autore accompagna il lettore, attraverso bellissime fotografie, in un percorso affascinante nel mondo dei \u201cgiganti verdi\u201d del territorio salentino, interrogandosi sul futuro che li [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8371,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10113"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10113"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10113\/revisions"}],"predecessor-version":[{"id":10115,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10113\/revisions\/10115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/8371"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}