{"id":101343,"date":"2016-10-29T00:06:00","date_gmt":"2016-10-28T22:06:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=101343"},"modified":"2016-10-28T10:02:45","modified_gmt":"2016-10-28T08:02:45","slug":"grazie-per-la-foto-314","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/10\/29\/grazie-per-la-foto-314\/","title":{"rendered":"GRAZIE PER LA FOTO"},"content":{"rendered":"<div>Nadia Murad Basee e Lamiya Aji Bashar, eroine della comunit\u00e0 Yazida perseguitata dall&#8217;Isis, hanno vinto il premio &#8220;Sakharov&#8221; 2016, assegnato dal Parlamento Europeo a persone e associazioni che si distinguono nella difesa dei diritti umani e delle libert\u00e0 fondamentali. Originarie del villaggio di Kocho nel Sinjar, nel nord dell&#8217;Iraq, le due donne hanno cominciato la loro battaglia di testimonianza dopo essere state rapite e rese schiave sessuali dai combattenti del califfato. Murad, gi\u00e0 destinataria del premio Vaclav Havel attribuito dal Consiglio d&#8217;Europa, sta lavorando anche al riconoscimento del genocidio degli Yazidi, una minoranza religiosa vittima dei fondamentalisti sunniti. Piccole e immense donne che rappresentano un esempio meraviglioso di resistenza e convinzione nel cambiamento contro le peggiori brutture del mondo.<\/div>\n<div>Grazie per la foto all&#8217;amica Antonella.<\/div>\n<div><\/div>\n<div><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/310x0_1477572332103.combo_sakharov.jpg\" alt=\"\" title=\"310x0_1477572332103.combo_sakharov\" class=\"aligncenter size-full wp-image-101344\" width=\"310\" height=\"160\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/310x0_1477572332103.combo_sakharov.jpg 310w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/310x0_1477572332103.combo_sakharov-300x155.jpg 300w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/10\/29\/grazie-per-la-foto-314\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/10\/29\/grazie-per-la-foto-314\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nadia Murad Basee e Lamiya Aji Bashar, eroine della comunit\u00e0 Yazida perseguitata dall&#8217;Isis, hanno vinto il premio &#8220;Sakharov&#8221; 2016, assegnato dal Parlamento Europeo a persone e associazioni che si distinguono nella difesa dei diritti umani e delle libert\u00e0 fondamentali. Originarie del villaggio di Kocho nel Sinjar, nel nord dell&#8217;Iraq, le due donne hanno cominciato la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":101344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/101343"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=101343"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/101343\/revisions"}],"predecessor-version":[{"id":101346,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/101343\/revisions\/101346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/101344"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=101343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=101343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=101343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}