{"id":101470,"date":"2016-10-29T13:55:43","date_gmt":"2016-10-29T11:55:43","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=101470"},"modified":"2016-10-29T13:55:43","modified_gmt":"2016-10-29T11:55:43","slug":"i-carabinieri-gli-trovano-un-arma-rubata-in-casa-denunciato-giovane-di-gallipoli","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/10\/29\/i-carabinieri-gli-trovano-un-arma-rubata-in-casa-denunciato-giovane-di-gallipoli\/","title":{"rendered":"I CARABINIERI GLI TROVANO UN&#8217; ARMA RUBATA IN CASA, DENUNCIATO GIOVANE DI GALLIPOLI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" title=\"20161029_110411\" class=\"alignleft size-medium wp-image-101471\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/20161029_110411-300x168.jpg\" \/>(g.m.)______Un giovane imprenditore di Gallipoli di 37 anni \u00e8 stato denunciato a piede libero per\u00a0ricettazione e detenzione illegale di armi.\u00a0Durante una perquisizione domiciliare compiuta all&#8217; alba di questa mattina, anche con l&#8217; ausilio \u00a0di un cane addestrato, i Carabinieri hanno trovato\u00a0a casa sua una pistola Walther PPK calibro 7,65, con due caricatori (nella foto), che \u00e8 poi risultata essere stata rubata nel febbraio dello scorso anno.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/10\/29\/i-carabinieri-gli-trovano-un-arma-rubata-in-casa-denunciato-giovane-di-gallipoli\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/10\/29\/i-carabinieri-gli-trovano-un-arma-rubata-in-casa-denunciato-giovane-di-gallipoli\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)______Un giovane imprenditore di Gallipoli di 37 anni \u00e8 stato denunciato a piede libero per\u00a0ricettazione e detenzione illegale di armi.\u00a0Durante una perquisizione domiciliare compiuta all&#8217; alba di questa mattina, anche con l&#8217; ausilio \u00a0di un cane addestrato, i Carabinieri hanno trovato\u00a0a casa sua una pistola Walther PPK calibro 7,65, con due caricatori (nella foto), che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":101471,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/101470"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=101470"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/101470\/revisions"}],"predecessor-version":[{"id":101473,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/101470\/revisions\/101473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/101471"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=101470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=101470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=101470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}