{"id":10192,"date":"2013-01-31T08:52:57","date_gmt":"2013-01-31T08:52:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10192"},"modified":"2013-01-31T08:56:14","modified_gmt":"2013-01-31T08:56:14","slug":"impianti-termici-il-comune-fa-chiarezza","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/31\/impianti-termici-il-comune-fa-chiarezza\/","title":{"rendered":"IMPIANTI TERMICI, IL COMUNE FA CHIAREZZA"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><em><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/31\/impianti-termici-il-comune-fa-chiarezza\/img_0285\/\" rel=\"attachment wp-att-10195\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/IMG_0285.jpg\" alt=\"\" width=\"1000\" height=\"631\" class=\"alignleft size-full wp-image-10195\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/IMG_0285.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/IMG_0285-300x189.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/em><\/p>\n<p><em>Intesa raggiunta oggi in un incontro tra l\u2019assessore alle Politiche Ambientali, <strong>Andrea Guido<\/strong> e i rappresentanti della societ\u00e0 magliese che ha effettuato i controlli sulle caldaie<br \/>\n<\/em>I controlli relativi ai sistemi di termoregolazione interna degli impianti nell\u2019ambito delle verifiche gestite dalla <strong>Societ\u00e0 Cooperativa V.I.T.<\/strong> di Maglie saranno effettuati seguendo i canoni ordinari, accertando cio\u00e8 l\u2019eventuale esistenza di fumi fuori norma immessi in atmosfera e non, piuttosto, la presenza di valvole termostatiche e di un cronotermostato o dello sbocco della canna fumaria al di sopra del tetto dell\u2019edificio.<\/p>\n<p>E\u2019 quanto stabilito nel corso della riunione tenutasi questa mattina nella sede dell\u2019Assessorato alle Politiche Ambientali del Comune di via Lombardia alla presenza dell\u2019assessore <strong>Andrea Guido <\/strong>e del dirigente del Settore Ambiente<strong>, Fernando Bonocuore e dei <\/strong>rappresentanti della societ\u00e0 magliese.<\/p>\n<p>L\u2019obiettivo, infatti, \u00e8 quello di alleggerire il carico di incombenze economiche che gravano sui cittadini leccesi, costretti a pagare negli ultimi tempi diversi balzelli.<\/p>\n<p>Nel corso della riunione odierna \u00e8 emerso che la V.I.T, la societ\u00e0 cooperativa affidataria del servizio del Comune di Lecce, durante i controlli effettuati nelle scorse settimane, avesse rilevato l\u2019obbligo di utilizzare valvole termostatiche su tutti i radiatori installati nonch\u00e9 l\u2019attivazione di un cronotermostato entrando cos\u00ec nel merito del sistema di termoregolazione interno, a prescindere dalle risultanze delle analisi sui fumi immessi in atmosfera dall\u2019impianto in questione. La spesa per le famiglie non dotate di questi dispositivi, comprensiva della tariffa dovuta alla societ\u00e0 affidataria del servizio, ammonterebbe a circa 800 euro.<\/p>\n<p><em>\u201cQuello che mi sta a cuore pi\u00f9 di ogni altra cosa &#8211; <\/em>ha commentato l\u2019assessore<strong> Andrea Guido <\/strong>&#8211; <em>\u00e8 la salute dei cittadini. Non vedo perch\u00e9 si debbano consentire simili vessazioni dal momento in cui l\u2019analisi dei fumi immessi nell\u2019aria risulti positiva e rientri nei parametri previsti dalla legge. Ho chiesto ai rappresentati della ditta di cominciare a pensare ad un eventuale riorganizzazione del servizio mentre, io, dal canto mio, con il mio staff, di qui a breve, predisporr\u00f2 una nuova campagna informativa per la cittadinanza per rimarcare l\u2019importanza dell\u2019efficienza e del soddisfacimento dei requisiti di legge per tutti gli impianti ai fini del risparmio energetico\u201d<\/em>.<\/p>\n<p>L\u2019assessore <strong>Andrea Guido<\/strong> interviene anche sul piano politico rilevando,<em> \u201cancora una volta, tentativi di strumentalizzazione da parte di alcuni esponenti dell\u2019opposizione consiliare.<\/em><em> Mi sembra che la vicenda sia stata risolta nella migliore maniera possibile salvaguardando non solo l\u2019ambiente e l\u2019aria che respiriamo in citt\u00e0 ma anche le tasche dei cittadini, non solo quelle di coloro che ancora non sono stati sottoposti ai controlli ma anche quelle di coloro i quali si sono visti gi\u00e0 accertare l\u2019anomalia tecnica in questione. Con i titolari degli impianti termici, infatti, \u00e8 stata concordata \u00a0anche la sospensione di ogni effetto derivante da accertamenti precedenti\u201d.<\/em><\/p>\n<p style=\"text-align: left\" align=\"center\"><em><br \/>\n<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/31\/impianti-termici-il-comune-fa-chiarezza\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/31\/impianti-termici-il-comune-fa-chiarezza\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Intesa raggiunta oggi in un incontro tra l\u2019assessore alle Politiche Ambientali, Andrea Guido e i rappresentanti della societ\u00e0 magliese che ha effettuato i controlli sulle caldaie I controlli relativi ai sistemi di termoregolazione interna degli impianti nell\u2019ambito delle verifiche gestite dalla Societ\u00e0 Cooperativa V.I.T. di Maglie saranno effettuati seguendo i canoni ordinari, accertando cio\u00e8 l\u2019eventuale [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10195,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10192"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10192"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10192\/revisions"}],"predecessor-version":[{"id":10194,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10192\/revisions\/10194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10195"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}