{"id":10263,"date":"2013-02-01T12:39:39","date_gmt":"2013-02-01T12:39:39","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10263"},"modified":"2013-02-01T12:39:39","modified_gmt":"2013-02-01T12:39:39","slug":"droga-nel-barattolo-arrestato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/droga-nel-barattolo-arrestato\/","title":{"rendered":"DROGA NEL BARATTOLO: ARRESTATO"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-10263 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/droga-nel-barattolo-arrestato\/2013-01-31-17-29-12\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/2013-01-31-17.29.12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/droga-nel-barattolo-arrestato\/de-salve-giorgio\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/De-Salve-Giorgio-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/droga-nel-barattolo-arrestato\/garofalo-valerio\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/GAROFALO-Valerio-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Nella serata del 30 gennaio u.s. i carabinieri della Stazione Carabinieri di Taviano hanno dato esecuzione all\u2019ordinanza di custodia in carcere SIEP n. 32\/2013 emessa in data 24 Gennaio 2013 dalla Procura della Repubblica di Lecce \u2013 Ufficio Esecuzione Penale nei confronti di:<\/p>\n<p>\u00fc\u00a0\u00a0Garofalo Valerio, cl. 64 di Taviano, coniugato, gi\u00e0 noto alle FF.PP.<\/p>\n<p>Che dovr\u00e0 scontare circa 2 anni e 8 mesi di reclusione per il reato di detenzione illegale di sostanze stupefacenti negli anni addietro.<\/p>\n<p>L\u2019arrestato, espletate le formalit\u00e0 di rito, \u00e8 stato tradotto presso al Casa Circondariale di Borgo San Nicola.<\/p>\n<p><em>DROGA NEL BARATTOLO: ARRESTATO<\/em><\/p>\n<p>Nella serata del 31 gennaio, invece, i carabinieri del Nucleo Operativo e Radiomobile della Compagnia carabinieri di Casarano hanno posto in essere una attivit\u00e0 di PG finalizzata al contrasto della detenzione e dello spaccio di stupefacente per cui, al termine di perquisizioni domiciliari e personali, \u00e8 stato tratto in arresto: per il reato di detenzione finalizzata allo spaccio di sostanze stupefacenti del tipo marijuana ed hashish:<\/p>\n<p><strong>De Salve Giorgio\u00a0<\/strong>cl. 79, residente a Matino, coniugato;<\/p>\n<p>Nella circostanza sono stati rinvenuti presso la sua abitazione, nel ripostiglio,\u00a0 occultati all\u2019interno di un scatola gr. 109 (centonove) di marijuana, gr. 16 ca di hashish nascosti in un barattolo all\u2019interno di un\u2019altra stanza dell\u2019abitazione, un bilancino di precisione e \u20acuro 190 probabile provento di pregresso spaccio.<\/p>\n<p>L\u2019arrestato, espletate le formalit\u00e0 di rito,\u00a0 \u00e8 stato accompagnato presso la sua abitazione in regime di arresti domiciliari su disposizione del sostituto procuratore di turno tempestivamente informato dell\u2019intero accaduto.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/droga-nel-barattolo-arrestato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/droga-nel-barattolo-arrestato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nella serata del 30 gennaio u.s. i carabinieri della Stazione Carabinieri di Taviano hanno dato esecuzione all\u2019ordinanza di custodia in carcere SIEP n. 32\/2013 emessa in data 24 Gennaio 2013 dalla Procura della Repubblica di Lecce \u2013 Ufficio Esecuzione Penale nei confronti di: \u00fc\u00a0\u00a0Garofalo Valerio, cl. 64 di Taviano, coniugato, gi\u00e0 noto alle FF.PP. Che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10263"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10263"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10263\/revisions"}],"predecessor-version":[{"id":10267,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10263\/revisions\/10267"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}