{"id":10272,"date":"2013-02-01T12:44:34","date_gmt":"2013-02-01T12:44:34","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10272"},"modified":"2013-02-01T12:44:34","modified_gmt":"2013-02-01T12:44:34","slug":"situazione-esplosiva-uil-lecce-propone-una-manifestazione-a-roma-per-sollecitare-il-governo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/situazione-esplosiva-uil-lecce-propone-una-manifestazione-a-roma-per-sollecitare-il-governo\/","title":{"rendered":"SITUAZIONE ESPLOSIVA, UIL LECCE PROPONE UNA MANIFESTAZIONE A ROMA PER SOLLECITARE IL GOVERNO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/situazione-esplosiva-uil-lecce-propone-una-manifestazione-a-roma-per-sollecitare-il-governo\/salvatore_giannetto-7\/\" rel=\"attachment wp-att-10273\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/salvatore_giannetto.jpg\" alt=\"\" width=\"727\" height=\"1024\" class=\"alignleft size-full wp-image-10273\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/salvatore_giannetto.jpg 727w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/salvatore_giannetto-212x300.jpg 212w\" sizes=\"(max-width: 727px) 100vw, 727px\" \/><\/a>BLOCCO CIG IN DEROGA<br \/>\n<\/strong>\u201cSiamo agli sgoccioli, la bomba sta per esplodere\u201d. Il segretario provinciale della Uil di Lecce, <strong>Salvatore Giannetto<\/strong>, commenta cos\u00ec l\u2019ennesimo sit-in di protesta che si \u00e8 svolto questa mattina davanti alla sede della Prefettura. \u201cNella sola provincia di Lecce \u2013 ricorda &#8211; sono ben settemila i lavoratori in cassa integrazione in deroga, molti dei quali da settembre scorso non percepiscono pi\u00f9 il sussidio indispensabile per mandare avanti le rispettive famiglie. La situazione rischia di degenerare \u2013 avverte &#8211; sono pronti ad atti estremi perch\u00e9 molti non hanno pi\u00f9 soldi nemmeno per comprare il pane\u201d.<\/p>\n<p style=\"text-align: left\" align=\"center\">\n\u201cSiamo di fronte ad una beffa \u2013 sostiene Giannetto &#8211; perch\u00e9 continuiamo ad assistere a ladrocini di vario genere, a sprechi della politica che bisogna drasticamente ridimensionare e non si riesce invece a trovare la copertura dei sussidi per questi lavoratori (che in Puglia sono oltre 50mila), cos\u00ec come non \u00e8 tollerabile che non si riesca ancora a fornire alcuna certezza sulla copertura della Cig in deroga per il 2013. A tutto questo \u2013 prosegue &#8211; si aggiungono un altro paradosso, quello dei tempi \u201cbiblici\u201d, causati da cavilli burocratici di vario genere, impiegati per far partire lavori gi\u00e0 appaltati alle aziende, come nel caso della della Regionale 8 o della Maglie-Otranto per il gruppo Palumbo che ha ben 300 operai in cassa integrazione\u201d.<\/p>\n<p>Di fronte ad una situazione cos\u00ec drammatica, la Uil di Lecce ritiene che non ci sia pi\u00f9 tempo da perdere e propone un\u2019iniziativa di protesta da organizzare a livello regionale. \u201c\u00c8 ora di andare a Roma a far sentire la nostra voce \u2013 tuona Giannetto \u2013 e fare pressione sul Governo affinch\u00e9 sani questa situazione. In primis, chiediamo di sbloccare subito l\u2019erogazione degli ammortizzatori almeno per i mesi di settembre, ottobre, novembre e dicembre, per poi riprogrammare la copertura per il 2013. Naturalmente \u2013 torna a ribadire il segretario della Uil di Lecce &#8211; questi sono problemi di carattere contingente e urgente, ma non possiamo vivere di sola cassa integrazione che prima o poi finir\u00e0, anzi sta gi\u00e0 finendo. Dobbiamo piuttosto lavorare sulla ricerca di politiche attive del lavoro \u2013 conclude &#8211; che possano aprire nuovi orizzonti lavorativi e offrire possibilit\u00e0 concrete di impiego soprattutto ai giovani\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/situazione-esplosiva-uil-lecce-propone-una-manifestazione-a-roma-per-sollecitare-il-governo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/01\/situazione-esplosiva-uil-lecce-propone-una-manifestazione-a-roma-per-sollecitare-il-governo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>BLOCCO CIG IN DEROGA \u201cSiamo agli sgoccioli, la bomba sta per esplodere\u201d. Il segretario provinciale della Uil di Lecce, Salvatore Giannetto, commenta cos\u00ec l\u2019ennesimo sit-in di protesta che si \u00e8 svolto questa mattina davanti alla sede della Prefettura. \u201cNella sola provincia di Lecce \u2013 ricorda &#8211; sono ben settemila i lavoratori in cassa integrazione in [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10273,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10272"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10272"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10272\/revisions"}],"predecessor-version":[{"id":10276,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10272\/revisions\/10276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10273"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}