{"id":102900,"date":"2016-11-20T00:08:30","date_gmt":"2016-11-19T23:08:30","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=102900"},"modified":"2016-11-18T13:55:18","modified_gmt":"2016-11-18T12:55:18","slug":"diario-del-giorno-dopo-ricorrenze-da-fare-lunedi-21","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/11\/20\/diario-del-giorno-dopo-ricorrenze-da-fare-lunedi-21\/","title":{"rendered":"DIARIO DEL GIORNO DOPO \/ RICORRENZE \/ LA FESTA DEGLI ALBERI A LECCE LUNEDI&#8217; 21"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"206\" title=\"alberi-martignano-2\" class=\"aligncenter size-medium wp-image-103126\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/11\/alberi-martignano-2-300x206.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/11\/alberi-martignano-2-300x206.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/11\/alberi-martignano-2-1024x704.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/11\/alberi-martignano-2-768x528.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/11\/alberi-martignano-2-1536x1055.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/11\/alberi-martignano-2.jpg 1959w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Luned\u00ec 21 novembre, dal pomeriggio, alla sera, a Lecce, all&#8217; Open Space di Piazza Sant&#8217; Oronzo, sono in programma svariate iniziative in occasione della \u201cGiornata Nazionale degli Alberi\u201d, riconosciuta\u00a0 dalla legge 10\/2013, con l\u2019obiettivo, attraverso la valorizzazione e la tutela dell\u2019ambiente e del patrimonio arboreo e dei boschi, di promuovere politiche di riduzione delle emissioni, la protezione del suolo, il miglioramento della qualit\u00e0 dell\u2019aria, la valorizzazione delle tradizioni legate all&#8217;albero nella cultura italiana e la vivibilit\u00e0 degli insediamenti urbani.<\/p>\n<p>In occasione di tale giornata l\u2019Assessorato alle Politiche Ambientali del Comune di Lecce, in collaborazione con l\u2019Associazione Valori e Rinnovamento, l\u2019Associazione per la Diffusione delle Piante tra Amatori (ADiPA), Compost Natura S.r.l. e Peperoncinoitalia.com organizzano a Lecce la prima edizione della Festa degli Alberi.<\/p>\n<p>Si tratta di una serie di iniziative previste, come detto,\u00a0per il pomeriggio e la sera di luned\u00ec 21 nella Sala Open Space di Palazzo Carafa e in Piazza Sant\u2019Oronzo, volte a promuovere la conoscenza dell\u2019ecosistema boschivo, la\u00a0tutela della biodiversit\u00e0 e il rispetto delle specie arboree, anche ai fini del mantenimento dell\u2019equilibrio tra comunit\u00e0 umana e ambiente naturale, al fine di favorire l\u2019adozione dei comportamenti quotidiani ecosostenibili.<\/p>\n<p>Alle 19, in particolare, ci sar\u00e0 la manifestazione &#8220;Salviamo gli ulivi del Salento&#8221;.<\/p>\n<p>Gli alberi rappresentano, infatti, da sempre un valore inestimabile per l\u2019umanit\u00e0. Sono custodi della nostra memoria e fonte di risorse preziose. Essi sono elementi fondamentali dell\u2019ecosistema e, in modo particolare nella citt\u00e0, contribuiscono significativamente a contrastare l\u2019inquinamento ambientale e a migliorare la qualit\u00e0 della nostra vita, sono simbolo di un millenario rapporto tra l\u2019uomo e la natura, fatto di rispetto e armonia.<\/p>\n<p>Interverranno: Andrea Guido, Assessore alle Politiche Ambientali del Comune; Wojtek Pankiewicz, Presidente del Movimento Culturale &#8220;Valori e Rinnovamento\u201d; Paolo Marini, Amministratore di Compost Natura S.r.l. ;Fabio Calogiuri, titolare di Peperoncinoitalia.com; Maria Luisa Quintaba, Responsabile di ADiPA Puglia;\u00a0i referenti della comunicazione di Monteco s.r.l.<\/p>\n<p>Saranno presenti, inoltre, alcuni artisti che si esibiranno nella Sala Open Space nel corso della manifestazione.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/11\/20\/diario-del-giorno-dopo-ricorrenze-da-fare-lunedi-21\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/11\/20\/diario-del-giorno-dopo-ricorrenze-da-fare-lunedi-21\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 21 novembre, dal pomeriggio, alla sera, a Lecce, all&#8217; Open Space di Piazza Sant&#8217; Oronzo, sono in programma svariate iniziative in occasione della \u201cGiornata Nazionale degli Alberi\u201d, riconosciuta\u00a0 dalla legge 10\/2013, con l\u2019obiettivo, attraverso la valorizzazione e la tutela dell\u2019ambiente e del patrimonio arboreo e dei boschi, di promuovere politiche di riduzione delle emissioni, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":103126,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/102900"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=102900"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/102900\/revisions"}],"predecessor-version":[{"id":103125,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/102900\/revisions\/103125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/103126"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=102900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=102900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=102900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}