{"id":10351,"date":"2013-02-02T15:08:35","date_gmt":"2013-02-02T15:08:35","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10351"},"modified":"2013-02-02T15:08:44","modified_gmt":"2013-02-02T15:08:44","slug":"vento-nuovo-a-lecce-cambiera-anche-il-rendimento-in-casa-col-treviso-di-gabriele-de-pandis","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/02\/vento-nuovo-a-lecce-cambiera-anche-il-rendimento-in-casa-col-treviso-di-gabriele-de-pandis\/","title":{"rendered":"VENTO NUOVO A LECCE : CAMBIERA&#8217; ANCHE IL RENDIMENTO IN CASA COL TREVISO?  &#8211; di Gabriele De Pandis"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/02\/vento-nuovo-a-lecce-cambiera-anche-il-rendimento-in-casa-col-treviso-di-gabriele-de-pandis\/lecce-sport\/\" rel=\"attachment wp-att-10352\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/lecce-sport.jpeg\" alt=\"\" width=\"778\" height=\"490\" class=\"alignleft size-full wp-image-10352\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/lecce-sport.jpeg 778w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/lecce-sport-300x188.jpg 300w\" sizes=\"(max-width: 778px) 100vw, 778px\" \/><\/a>Ne son successe tante da quella dipartita a San Marino dove si \u00e8 toccato il punto pi\u00f9 basso dell\u2019anno del campionato.<br \/>\nIn primis Franco Lerda \u00e8 stato sollevato dall\u2019incarico di allenatore, per essere sostituito dall\u2019allenatore della Berretti delle meraviglie Toma. Del mister magliese si sa tutto e niente, sono noti i suoi passati da vice di Antonio Conte sulle panchine di Bari, Arezzo e Atalanta. Toma cercher\u00e0 di approntare un gioco iperoffensivo con un 4-2-4 , quello schema caro a Conte e al suo Bari dell\u2019annata 2009.<br \/>\nIl calciomercato di gennaio ha poi portato in Salento tre elementi interessati quali D\u2019Ambrosio, Dram\u00e8 e Fatic.<\/p>\n<p>Dario D\u2019Ambrosio, terzino destro con spiccate propensioni offensive, \u00e8 gi\u00e0 noto al Lecce per la zuccata con la quale ha fissato il punteggio di Lumezzane-Lecce sul 2-1. Il suo arrivo pu\u00f2 suonare come una bocciatura per il neotrentenne Ronaldo Vanin , ma il presidente Tesoro ha dichiarato che un po\u2019 di concorrenza pu\u00f2 far solo bene al terzino brasiliano ex Torino e Sorrento.<\/p>\n<p>Ousmane Dram\u00e8 \u00e8 forse il colpo pi\u00f9 altisonante messo a segno da Antonio Tesoro. L\u2019ex Padova \u00e8 stato vicino due anni fa alla serie A con la squadra biancoscudata. Ousmane pu\u00f2 ricoprire benissimo tutti i ruoli sulla fascia sinistra. Nell\u2019ipotetico 4-2-4 visto da Toma per\u00f2 \u00e8 probabile il suo impiego nel quartetto offensivo. Dotato di gran corsa e sopraffina tecnica , \u00e8 il pi\u00f9 accreditato per partire nell\u2019undici titolare gi\u00e0 da subito.<\/p>\n<p>Ivan Fatic , nonostante la sua giovane et\u00e0 (24) , vanta gi\u00e0 innumerevoli esperienze in A e B con le maglie di Chievo, Vicenza, Salernitana. Il difensore scuola Inter \u00e8 inoltre nel giro della nazionale montenegrina sempre vicina al grande approdo alle fasi finali delle grandi competizioni europee. Sicuramente la coppia centrale Esposito-Di Maio avr\u00e0 un concorrente molto insidioso.<\/p>\n<p>Il campionato riprender\u00e0 domenica con la sfida del \u201cVia Del Mare\u201d contro il Treviso fanalino di coda del campionato. \u00c8 una partita dove il debuttante mister Toma avr\u00e0 tutto da perdere viste le disastrose condizioni della squadra della Marca, protagonista di un campionato deludente dove ai discreti proclami iniziali \u00e8 seguita una realt\u00e0 ben diversa: il massimo obiettivo dei biancocelesti ora \u00e8 evitare l\u2019ultimo posto (lotta tra poveri con la Tritium) e cercare di giocarsi tutto nei playout. L\u2019unica cessione degna di nota del Lecce \u00e8 stata proprio a favore dei trevigiani infatti proprio alla corte di mister Ruotolo \u00e8 finito il difensore versatile Daniel Semenzato.<\/p>\n<p>Il ruolino della squadra lontano dal \u201cTenni\u201d \u00e8 pauroso: solo due punti , nessun successo e sette sconfitte anche se spicca l\u2019ultima esibizione a casa (ahim\u00e8) della neocapolista Trapani, dove la squadra della Marca \u00e8 stata sconfitta solo con una doppia inferiorit\u00e0 numerica per 3-2. In ogni caso , anche confidando nell\u2019inesattezza dei numeri, il Lecce ha di fronte un impegno dove mancare i tre punti sarebbe un delitto data la crisi in cui versa la squadra di Mister Ruotolo che ha colto l\u2019unica vittoria del campionato il 22.12 al \u201cTenni\u201d contro la Reggiana. In casa all\u2019unica vittoria contro gli emiliani seguono 4 pari e 5 reti. La media realizzativa \u00e8 sconcertante infatti i trevigiani segnano in media un gol ogni due partite (0,47) a fronte di una difesa un po\u2019 ballerina con 35 gol subiti.<\/p>\n<p>Ruotolo cercher\u00e0 di tentare il tutto per tutto a Lecce disponendo i suoi uomini con un 4-3-3 davanti al portiere Gianmarco Campironi. La difesa in linea vede impegnati prevalentemente i centrali Cernuto e l\u2019ex Mariano Stendardo. Sar\u00e0 probabile poi l\u2019impiego del fresco Semenzato a destra dove fino ad ora ha trovato posto il 21enne Andrea Brunetti. Completa il reparto Beccia. A centrocampo aria di riforme per Ruotolo infatti il mercato di gennaio ha portato via dalla Marca i centrocampisti quasi sempre impiegati Pierangelo Tarantino (Fano) e Salvi (Sorrento). Il reparto che affronter\u00e0 il Lecce sar\u00e0 probabilmente formato da Spinosa, Rosaia e dal vincitore del ballottaggio tra Walter Piccioni e il giovane sloveno Komac. Davanti occhio al sempreverde Nazzareno Tarantino (a segno all\u2019andata), capocannoniere dei trevigiani con 7 reti, a sinistra. Sulla parte opposta del tridente ballottaggio tra il ghanese Leandro Kyarametang ed il giovane Leandro Rizzo. Al centro trover\u00e0 posto il \u201ccentroboa\u201d Picone.<\/p>\n<p>C\u2019\u00e8 da vedere se Ruotolo , nonostante il modulo, opter\u00e0 per un atteggiamento offensivo anche al cospetto del pi\u00f9 attrezzato Lecce, ora pi\u00f9 che mai costretto a vincere.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/02\/vento-nuovo-a-lecce-cambiera-anche-il-rendimento-in-casa-col-treviso-di-gabriele-de-pandis\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/02\/vento-nuovo-a-lecce-cambiera-anche-il-rendimento-in-casa-col-treviso-di-gabriele-de-pandis\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Ne son successe tante da quella dipartita a San Marino dove si \u00e8 toccato il punto pi\u00f9 basso dell\u2019anno del campionato. In primis Franco Lerda \u00e8 stato sollevato dall\u2019incarico di allenatore, per essere sostituito dall\u2019allenatore della Berretti delle meraviglie Toma. Del mister magliese si sa tutto e niente, sono noti i suoi passati da vice [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10352,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10351"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10351"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10351\/revisions"}],"predecessor-version":[{"id":10357,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10351\/revisions\/10357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10352"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}