{"id":10498,"date":"2013-02-06T08:55:19","date_gmt":"2013-02-06T08:55:19","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10498"},"modified":"2013-02-06T08:55:19","modified_gmt":"2013-02-06T08:55:19","slug":"su-torre-venere-lassessore-guido-tira-le-orecchie-al-governo-vendola","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/06\/su-torre-venere-lassessore-guido-tira-le-orecchie-al-governo-vendola\/","title":{"rendered":"SU TORRE VENERE, L&#8217;ASSESSORE GUIDO TIRA LE ORECCHIE AL GOVERNO VENDOLA"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><em><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/06\/su-torre-venere-lassessore-guido-tira-le-orecchie-al-governo-vendola\/guido-andrea-viso\/\" rel=\"attachment wp-att-10499\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/guido-andrea-VISO.jpg\" alt=\"\" width=\"779\" height=\"1000\" class=\"alignleft size-full wp-image-10499\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/guido-andrea-VISO.jpg 779w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/guido-andrea-VISO-233x300.jpg 233w\" sizes=\"(max-width: 779px) 100vw, 779px\" \/><\/a>ECCO COSA CI FA SAPERE L&#8217;ASSESSORE AL COMUNE DI LECCE ANDREA GUIDO.<br \/>\n<\/em><em>\u201cSiamo ancora in attesa di conoscere \u2013 ammesso che ci sia \u2013 il disciplinare d\u2019uso e delle tutela ambientale del Poligono di Tiro\u201d<br \/>\n<\/em><em>\u201cHo richiesto formalmente alla <strong>Scuola di Cavalleria<\/strong> l\u2019accesso al <strong>Disciplinare d\u2019Uso<\/strong> e al <strong>Disciplinare per la Tutela Ambientale<\/strong> del <strong>Poligono di Torre Veneri: <\/strong>\u00e8 passato pi\u00f9 di un mese ed ancora non ci \u00e8 pervenuta alcuna risposta. Come dovrei interpretare questo silenzio? L\u2019unica spiegazione ammissibile \u00e8 che, con ogni probabilit\u00e0, questi atti, previsti dalla legge, presentino delle imprecisioni o delle incongruenze o, addirittura, non siano mai stati redatti\u201d.<\/em><\/p>\n<p>Sono parole dure quelle rivolte dall\u2019assessore alle Politiche Ambientali del Comune di Lecce, <strong>Andrea Guido<\/strong> all\u2019amministrazione Vendola. I due documenti a cui fa riferimento Guido &#8211; il primo di pertinenza delle Amministrazioni centrale e regionale, il secondo delle Forze Armate, ma da redigere di concerto con il Comitato Misto Paritetico a cui prendono parte Consiglieri ed Assessori delegati dal Presidente della Giunta Regionale e che dovrebbe essere il baluardo degli interessi delle popolazioni nel cui territorio ricadono i rispettivi poligoni di tiro &#8211; trovano fondamento nella legge n.104 del 1990.<\/p>\n<p>Secondo tale provvedimento viene demandata \u00a0alle Regioni e all\u2019Autorit\u00e0 Militare la stipula di disciplinari d\u2019uso per le aree addestrative terrestri, marittime ed aeree. <em>\u201cIn Toscana e nelle Marche, per quanto riguarda il Poligono di Tiro Permanente di Carpegna &#8211;<\/em> spiega l\u2019assessore <strong>Andrea Guido<\/strong> &#8211;<em> entrambi i disciplinari sono stati adottati e la salvaguardia ambientale e la salute dei cittadini \u00e8 stata garantita. Nella fattispecie, gli enti fruitori del Poligono, grazie ai Disciplinari approvati, hanno l\u2019obbligo di attuare tutte le misure necessarie per assicurare la totale bonifica da eventuali residuati esplosivi nell\u2019area attiva del poligono al termine delle esercitazioni a fuoco e di attuare tutte le misure necessarie per evitare danni alla vegetazione arborea e alla fauna in generale\u201d.<\/em><\/p>\n<p>Il Poligono di Torre Veneri, un lembo tra Frigole e San Cataldo che si affaccia sull\u2019Adriatico, \u00e8 incastonato nei 160 ettari di zona SIC (sito di interesse comunitario) e rappresenta un sito di notevole pregio naturalistico che confina a nord con il Parco di Rauccio e, a sud, con la riserva naturale delle Cesine.<\/p>\n<p>Di recente l\u2019Assessorato alle Politiche Ambientali ha avuto notizia che entro il 2015 il Poligono di Torre Veneri sar\u00e0 sostituito con un Centro di simulazione virtuale. Le esercitazioni militari a fuoco lasceranno definitivamente la scena a dei sistemi computerizzati. <em>\u201cNe prendo atto con soddisfazione<\/em> \u2013 ha concluso il suo intervento <strong>Andrea Guido<\/strong> \u2013 <em>un pensiero in meno, senza ombra di dubbio. Anche se non ho mai cercato soluzioni cos\u00ec estreme come la chiusura del Poligono. Si tratta, ad ogni buon conto, del primo passo per far tornare fruibile un area dal cos\u00ec alto valore naturalistico e paesaggistico. Ci\u00f2 che pi\u00f9 mi ha fatto riflettere nel corso di questa vicenda, \u00e8 stato l\u2019aver appurato la totale mancanza di interesse per la salvaguardia del nostro territorio e della salute dei nostri cittadini da parte dell\u2019Amministrazione regionale guidata da Vendola, che, ancora una volta, a mio avviso, ha dimostrato di non saper tradurre in fatti e interventi fattivi tutta quell\u2019attenzione per i temi dell\u2019ecologia che continuamente millanta di avere\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/06\/su-torre-venere-lassessore-guido-tira-le-orecchie-al-governo-vendola\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/06\/su-torre-venere-lassessore-guido-tira-le-orecchie-al-governo-vendola\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>ECCO COSA CI FA SAPERE L&#8217;ASSESSORE AL COMUNE DI LECCE ANDREA GUIDO. \u201cSiamo ancora in attesa di conoscere \u2013 ammesso che ci sia \u2013 il disciplinare d\u2019uso e delle tutela ambientale del Poligono di Tiro\u201d \u201cHo richiesto formalmente alla Scuola di Cavalleria l\u2019accesso al Disciplinare d\u2019Uso e al Disciplinare per la Tutela Ambientale del Poligono [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10498"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10498"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10498\/revisions"}],"predecessor-version":[{"id":10501,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10498\/revisions\/10501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10499"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}