{"id":10520,"date":"2013-02-06T09:23:10","date_gmt":"2013-02-06T09:23:10","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10520"},"modified":"2013-02-06T09:23:10","modified_gmt":"2013-02-06T09:23:10","slug":"in-tre-con-un-kg-di-marijuana","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/06\/in-tre-con-un-kg-di-marijuana\/","title":{"rendered":"IN TRE CON UN KG. DI MARIJUANA"},"content":{"rendered":"<div style=\"text-align: left\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/06\/in-tre-con-un-kg-di-marijuana\/napoletano-roberto\/\" rel=\"attachment wp-att-10521\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/NAPOLETANO-ROBERTO.jpg\" alt=\"\" width=\"718\" height=\"502\" class=\"alignleft size-full wp-image-10521\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/NAPOLETANO-ROBERTO.jpg 718w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/NAPOLETANO-ROBERTO-300x209.jpg 300w\" sizes=\"(max-width: 718px) 100vw, 718px\" \/><\/a>Nella serata di ieri a Otranto, i militari della locale Stazione carabinieri, nel corso di un predisposto servizio di controllo del territorio finalizzato al contrasto degli stupefacenti, hanno arrestato in flagranza di reato per detenzione di sostanze stupefacenti:<br \/>\n<strong>Vergine Emiliano<\/strong>, 36enne da Trepuzzi, disoccupato, pluripregiudicato;<br \/>\n<strong>Napoletano Roberto<\/strong>, 27enne da Squinzano, allevatore, pluripregiudicato;<br \/>\ne deferivano in stato libero per concorso nel medesimo reato,\u00a0<strong>N.L.<\/strong>, 28enne, incensurata.I militari una volta fermati i tre e verificati i precedenti di polizia di due dei tre occupanti e la presenza priva di giustificazioni in quei luoghi del terzetto, hanno proceduto alla perquisizione personale e veicolare. Non sono valse a dissuadere i militari dalle loro intenzioni, le particolari condizioni della donna \u2013 in stato interessante \u2013 denunciata insieme ai due \u00a0n\u00e9 le giustificazioni addotte. A bordo dell\u2019autovettura a noleggio, a seguito di accurata perquisizione personale e veicolare veniva rinvenuto, celato sotto uno dei sedili, un involucro contenente\u00a0\u00a0<strong>kg.1,04<\/strong>\u00a0di<strong>marijuana<\/strong>. E non \u00e8 un caso che i tre avessero preso un auto a noleggio; infatti un paio di giorni fa i carabinieri di Squinzano avevano sorpreso proprio Napoletano Roberto alla guida di un\u2019auto senza patente, poich\u00e9 revocata denunciandolo l\u2019indomani perch\u00e9 ancora una volta sorpreso alla guida dello stesso mezzo, nel frattempo sottoposto a fermo amministrativo e quindi poi sequestrato. Gli arrestati sono stati associati alla Casa Circondariale<\/div>\n<p><strong>\u00a0<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/06\/in-tre-con-un-kg-di-marijuana\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/06\/in-tre-con-un-kg-di-marijuana\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nella serata di ieri a Otranto, i militari della locale Stazione carabinieri, nel corso di un predisposto servizio di controllo del territorio finalizzato al contrasto degli stupefacenti, hanno arrestato in flagranza di reato per detenzione di sostanze stupefacenti: Vergine Emiliano, 36enne da Trepuzzi, disoccupato, pluripregiudicato; Napoletano Roberto, 27enne da Squinzano, allevatore, pluripregiudicato; e deferivano in [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10521,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10520"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10520"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10520\/revisions"}],"predecessor-version":[{"id":10523,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10520\/revisions\/10523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10521"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}