{"id":105379,"date":"2016-12-12T15:00:11","date_gmt":"2016-12-12T14:00:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=105379"},"modified":"2016-12-12T18:55:38","modified_gmt":"2016-12-12T17:55:38","slug":"ultimora-gentiloni-atteso-alle-1730-al-quirinale-per-la-lista-dei-ministri","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/12\/12\/ultimora-gentiloni-atteso-alle-1730-al-quirinale-per-la-lista-dei-ministri\/","title":{"rendered":"ULTIM&#8217;ORA \/ PAOLO GENTILONI ATTESO ALLE 17.30 AL QUIRINALE PER LA LISTA DEI MINISTRI"},"content":{"rendered":"<p>(G.A.)______<\/p>\n<p><strong>ROMA-\u00a0<\/strong>&#8220;Ho chiesto al presidente della\u00a0Repubblica di essere ricevuto per illustrargli il lavoro svolto.\u00a0Salir\u00f2 al Quirinale alle 17.30&#8221;. Lo ha detto il presidente\u00a0incaricato Paolo Gentiloni al termine delle consultazioni alla\u00a0Camera.\u00a0Il presidente incaricato oggi ha incontrato alla Camera le delegazioni di\u00a0Fratelli d&#8217;Italia, Svp, Civici Innovatori, gruppo per le Autonomie, Conservatori e Riformisti e Area Popolare e Forza\u00a0Italia, Gal e Pd.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"161\" title=\"640x344_1481555396175.Gentiloniannuncio\" class=\"alignleft size-medium wp-image-105381\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/640x344_1481555396175.Gentiloniannuncio-300x161.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/640x344_1481555396175.Gentiloniannuncio-300x161.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/640x344_1481555396175.Gentiloniannuncio.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Ho cercato conciliare tempi stretti e ascolto forze politiche &#8220;Ho cercato di conciliare l&#8217;esigenza\u00a0di tempi molto stretti che era molto chiara nelle parole del\u00a0presidente Mattarella e nella esigenza del Paese con la necessit\u00e0\u00a0di ascoltare le forze parlamentari, le loro idee e le loro\u00a0proposte. Rispetto chi ha preannunciato il sostegno al governo e\u00a0chi ha preannunciato un atteggiamento di opposizione&#8221;.<\/p>\n<p>Le opposizioni si sfilano. Inevitabile registrare &#8220;l&#8217;indisponibilit\u00e0&#8221; delle maggiori forze di opposizione a condividere un orizzonte di responsabilit\u00e0. Il suo esecutivo, quindi, si muover\u00e0 &#8211; sia pur &#8220;non per scelta&#8221;- nel quadro del governo e della maggioranza uscente.<\/p>\n<p>Il ministro degli Esteri del Governo uscente si mette subito a lavoro, quindi, per definire composizione e programma della nuova squadra, partendo dal quadro &#8220;ampio e articolato&#8221; delle consultazioni svolte dal Capo dello Stato, senza per\u00f2 sentire in prima persona i rappresentanti dei gruppi parlamentari.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/12\/12\/ultimora-gentiloni-atteso-alle-1730-al-quirinale-per-la-lista-dei-ministri\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/12\/12\/ultimora-gentiloni-atteso-alle-1730-al-quirinale-per-la-lista-dei-ministri\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(G.A.)______ ROMA-\u00a0&#8220;Ho chiesto al presidente della\u00a0Repubblica di essere ricevuto per illustrargli il lavoro svolto.\u00a0Salir\u00f2 al Quirinale alle 17.30&#8221;. Lo ha detto il presidente\u00a0incaricato Paolo Gentiloni al termine delle consultazioni alla\u00a0Camera.\u00a0Il presidente incaricato oggi ha incontrato alla Camera le delegazioni di\u00a0Fratelli d&#8217;Italia, Svp, Civici Innovatori, gruppo per le Autonomie, Conservatori e Riformisti e Area Popolare e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":105381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/105379"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=105379"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/105379\/revisions"}],"predecessor-version":[{"id":105409,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/105379\/revisions\/105409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/105381"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=105379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=105379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=105379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}