{"id":10544,"date":"2013-02-07T07:48:38","date_gmt":"2013-02-07T07:48:38","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10544"},"modified":"2013-02-07T07:48:38","modified_gmt":"2013-02-07T07:48:38","slug":"pietro-mascagni-zanetto-cavalleria-rusticana","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/pietro-mascagni-zanetto-cavalleria-rusticana\/","title":{"rendered":"Pietro Mascagni  Zanetto  Cavalleria Rusticana"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/pietro-mascagni-zanetto-cavalleria-rusticana\/mirabella\/\" rel=\"attachment wp-att-10545\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/mirabella.jpg\" alt=\"\" width=\"205\" height=\"212\" class=\"alignleft size-full wp-image-10545\" \/><\/a>Venerd\u00ec 8 Febbraio 2013, ore 20,45 \u00a0&#8211; \u00a0<\/strong><strong>Domenica 10 Febbraio 2013, ore 18.00 \u00a0&#8211;\u00a0<\/strong><strong>Teatro Politema Greco di Lecce<br \/>\n<\/strong>Puntuale ad un appuntamento prestigioso ed atteso, anche quest\u2019anno la tradizionale Stagione Lirica, la 44esima, richiama chi crede alla bellezza ed alla grandezza della musica. Bellezza e grandezza che sono in special modo della nostra fulgida tradizione operistica: pagine che portano il senso ed il sentimento della italianit\u00e0 in tutto il mondo.<br \/>\nL\u2019ottimo livello della direzione artistica e quello di cantanti ed orchestrali e di tutti coloro che hanno lavorato e lavorano alla realizzazione dell\u2019evento assicurano una produzione di prestigiosa qualit\u00e0. Questo nonostante le difficolt\u00e0 che l\u2019operazione presentava nel tempo di una crisi che continuiamo ad attraversare.<br \/>\nUn pensiero cordiale va a quanti, da spettatori competenti ed appassionati, partecipano alle rappresentazioni e ne sostengono le proposte artistiche.<br \/>\nA tutti l\u2019augurio che il messaggio della grande musica sia sempre pi\u00f9 accolto e rechi gioia e serenit\u00e0 nel cuore di tutti.<\/p>\n<p>Antonio Gabellone<br \/>\nPresidente della Provincia<\/p>\n<p>Ancora una stagione lirica di prestigio, la 44esima, che quest\u2019anno punta particolarmente l\u2019attenzione su Verdi e Mascagni per celebrare degnamente i 200 ed i 150 anni dalla loro nascita.Il programma verdiano presenta l\u2019intensa <em>Messa da requiem<\/em> e due opere popolarissime come <em>Traviata<\/em> e <em>Un ballo in maschera<\/em>; quello di Mascagni la <em>Cavalleria Rusticana <\/em>e un\u2019opera come <em>Zanetto <\/em>non frequente sul palcoscenico della lirica.<br \/>\nL\u2019Assessorato alla Cultura da me gestito presenta con orgoglio questa nuova stagione alla quale ci si \u00e8 accinti con qualche timore per le note difficolt\u00e0 economiche ma con la risolutezza che l\u2019impegno della stagione richiedeva. Sotto la guida del nuovo Direttore Artistico Sergio Rendine si apre una stagione ricca di promesse e di grande qualit\u00e0 nell\u2019impostazione e nella realizzazione.<br \/>\nCi auguriamo che la cultura sia messaggera di traguardi sempre pi\u00f9 alti, di iniziative sempre pi\u00f9 incisive nella nostra societ\u00e0.<br \/>\nUn augurio nel nome della musica.<\/p>\n<p>Simona Manca<br \/>\nV. Presidente\/Assessore Prov.le alla Cultura<\/p>\n<p style=\"text-align: left\" align=\"center\">La 44ma Stagione Lirica Tradizionale della Provincia di Lecce mi vede impegnato per la prima volta a Lecce come Direttore Artistico. Sar\u00e0 una Stagione nel segno della celebrazione del bicentenario della nascita di Giuseppe Verdi (uno dei pi\u00f9 grandi geni musicali di ogni tempo). Pensare che qualche grande Teatro italiano abbia voluto ridimensionare questa festa dell&#8217;umanit\u00e0 fa sorridere di un sorriso amaro verso un provincialismo snob (nel senso di Sine NOBilitate) che alberga nel cuore di certi personaggi, al di l\u00e0 dei luoghi e delle patrie. A Lecce no. W Verdi, con determinazione e orgoglio.<br \/>\nQuindi, nel giorno della morte del Maestro, il 27 gennaio, nella Cattedrale di Lecce, eseguiremo il suo monumentale <em>Requiem,<\/em> che ci piace pensare, per una volta, non composto per la morte di Manzoni, ma per se stesso, un po&#8217; come lo sono tutti i Requiem dei giganti della musica, da Mozart a Faur\u00e9, da Brahms a Britten. Direttore d&#8217;eccezione, Il grande John Neshling. Cast d&#8217;altissimo livello.<\/p>\n<p>La Stagione, specificatamente d&#8217;Opera, comincer\u00e0 nel segno di un&#8217;altra importante commemorazione: il 150\u00b0 dalla nascita di Pietro Mascagni, con l&#8217;atto unico &#8220;raro&#8221; di Zanetto e con la &#8220;planetaria&#8221; <em>Cavalleria Rusticana<\/em>. Direttore Paolo Olmi, regista Michele Mirabella. Seguiranno, ancora nel segno di Verdi, <em>Un ballo in maschera<\/em>, diretta da un volto noto a Lecce, Filippo Zigante, mio predecessore alla direzione artistica, e con la regia di Antonio De Lucia, regista di fama internazionale. Infine chiuder\u00e0 la Stagione <em>La traviata<\/em> con la regia di un mito assoluto, il coreografo, mimo, regista Lindsay Kemp, scopritore di David Bowie, autore dell&#8217;indimenticabile Flowers e dell&#8217;altrettanto indimenticabile successo mondiale, Alice (perdonate la vanit\u00e0, con musica mia). Il direttore sar\u00e0 il giovane Chung, figlio del grande Miun Chung, che sta avendo una fulminante carriera internazionale in Corea, Giappone, Cina, Stati Uniti. A Lecce, con tutta la risonanza internazionale che ne conseguir\u00e0, far\u00e0 il suo debutto assoluto in Europa. Violetta e Alfredo saranno tra i pi\u00f9 prestigiosi: Cinzia Forte e Massimiliano Pisapia.<\/p>\n<p>Voglio inoltre annunciarvi una bella novit\u00e0: ogni Opera da noi prodotta sar\u00e0 portata e replicata al Teatro di Brindisi, nel segno di un Teatro di Lecce che vuole espandersi come servizio artistico e culturale anche fuori dai confini della citt\u00e0 e della provincia. Con l&#8217;augurio di diffondere pi\u00f9 arte possibile.<\/p>\n<p>Per chiudere, voglio ringraziare i miei predecessori che tante cose hanno fatto per questo Ente Lirico, e tutto lo staff, il Direttore di Produzione Antonio De Lucia, il dirigente alle Politiche culturali, il dott. Antonio Lepore, quindi i funzionari Salvatore Viva e Francesca De Vito, e la segretaria di produzione Annalisa Nastrini. E tutti gli altri collaboratori, dentro e fuori il palcoscenico. Senza di loro la Stagione non avrebbe potuto prendere la forma e il livello che questa citt\u00e0, con la sua storica e gloriosa tradizione lirica, merita, e che speriamo di aver raggiunto. Un ringraziamento, infine, ma non per ultimi, al Presidente della Provincia Antonio Gabellone e alla Vicepresidente e Assessore alla Cultura Simona Manca, per la fiducia accordatami, ma soprattutto per il sostegno che hanno deciso di avere nei confronti dell&#8217;Arte, considerandola, finalmente e nonostante le difficolt\u00e0 contemporanee, un bene primario della civilt\u00e0.<\/p>\n<p>Vi auguro, dunque, buona lirica a Lecce, con la speranza di potervi offrire una sorpresa bella bella per l&#8217;estate, possibilit\u00e0 economiche permettendo.<\/p>\n<p>Sergio Rendine<br \/>\nDirettore Artistico<\/p>\n<p style=\"text-align: left\" align=\"center\">\u00a0<strong>Venerd\u00ec 8 Febbraio 2013, ore 20,45 \u00a0&#8211;\u00a0<\/strong><strong>Domenica 10 Febbraio 2013, ore 18.00 \u00a0 \u00a0<\/strong><strong>Zanetto<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\">Opera in un atto da Le Passant, di Fran\u00e7ois Copp\u00e9e \u00a0&#8211;\u00a0Riduzione di Giovanni Targioni-Tozetti e Guido Menasci &#8211;\u00a0<strong>Musica di Pietro Mascagni &#8211;\u00a0<\/strong>Edizioni Sonzogno<br \/>\nSilvia<strong> Gabriella Costa &#8211;\u00a0<\/strong>Paggio <strong>Antonella Colaianni<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>\u00a0<\/strong><strong>Cavalleria Rusticana\u00a0<\/strong>Melodramma in un atto &#8211;\u00a0Libretto di G. Targioni \u2013 Tozzetti e G. Menasci &#8211;\u00a0Musica di <strong>Pietro Mascagni &#8211;\u00a0<\/strong>Edizioni Sonzogno<\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>\u00a0<\/strong>Santuzza\u00a0 <strong>Nila Masala<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>Luisella De Pietro<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\">Turiddu<strong> Angelo Villari<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>Vincenzo Sarinelli<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\">Lola <strong> Antonella Colaianni<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\">Alfio <strong> Giuseppe Altomare<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\">Mamma Lucia <strong> Manuela Rizzo<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>\u00a0<\/strong>Regista<\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>Michele Mirabella<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>\u00a0<\/strong><strong>Orchestra \u201cTito Schipa\u201d di Lecce<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>Coro Lirico di Lecce<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>\u00a0<\/strong>Maestro concertatore e Direttore d\u2019Orchestra<\/p>\n<p style=\"text-align: left\" align=\"center\">\n<p style=\"text-align: left\" align=\"center\"><strong>Paolo Olmi<\/strong><strong><\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\">Maestro del Coro<\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>Emanuela Di Pietro<\/strong><\/p>\n<p style=\"text-align: left\" align=\"center\"><strong>\u00a0<\/strong><strong>INTERPRETI<br \/>\n<\/strong><strong>Gabriella Costa (Silvia, Zanetto)<\/strong><\/p>\n<p>Soprano, si perfeziona in canto in Olanda, in Francia e in Italia. Vincitrice del Concorso Internazionale \u201cCilea\u201d e del Concorso Nazionale \u201cCitt\u00e0 di Conegliano Veneto\u201d, debutta in campo operistico nel ruolo di Gilda nel Rigoletto di Verdi, cui hanno fatto seguito numerosi impegni in opere di Mozart, Donizetti, Rossini, Paisiello, Cimarosa, Cherubini, nei teatri La Fenice di Venezia, Opera di Roma, Verdi di Trieste, Regio di Parma, Massimo di Palermo etc., con direttori quali: J. Tate, G. Gelmetti, G. Ferro, A. Fischer, L\u00fc Ja, V. Yurovsky, L. Hager, I. Karabtchevsky, F. Welser-M\u00f6st, K. Weise, K.L. Wilson, H. Soudant, L. Guschlbauer, C. Desderi, S.A. Reck e con registi quali And\u00f2, Barberio Corsetti, Gregoretti, Krief, Miller, Puggelli, Pressburger, Scaparro. Tra le incisioni discografiche si segnalano: Musiche di Malipiero (Nuova Fonit Cetra), Vespro per lo Stellario della Beata Vergine di Rubino (K617), Messa in Do Minore di Mozart, Missa Cellensis di Haydn, versione ritmica italiana, Vedrai Vedrai&#8230; Omaggio alla Canzone d\u2019Autore italiana da Tenco a Battisti, Il Matrimonio Segreto di Cimarosa (Naxos).<br \/>\n<strong>Nila Masala (Santuzza, Cavalleria Rusticana)<\/strong><\/p>\n<p>Soprano. Nata a Sassari nel 1973, si diploma in Canto Lirico presso il Conservatorio \u201cLuisa D\u2019Annunzio\u201d di Pescara. Si perfeziona presso l\u2019Ateneo Internazionale della Lirica di Sulmona, seguendo i prestigiosi corsi di perfezionamento per cantanti lirici tenuti da docenti quali Mirella Freni, Gianni Raimondi,Gabriella Tucci e Dario Lucantoni.Componente del Trio Nice(Soprano e Pianoforte a 4 mani) dalla sua formazione.Dal 2000 al 2006 \u00e8 stata Artista del Coro del Teatro Marrucino di Chieti. Debutta il ruolo di Bianca ne La Villegne di G. Albanese a Ortona.E\u2019 stata la Contessa de Le Nozze di Figaro di Mozart al Teatro di Vasto (Ch). Interprete solista nella Passio et Resurrectio di S. Rendine presso la Cattedrale di San Giustino a Chieti nel 2006 \u00e8 inoltre soprano solista nella Petite Messe Solennelle di Rossini e nella Nona Sinfonia di Beethoven a Bari. E\u2019 Artista del Coro della Fondazione del Teatro Petruzzelli di Bari, e del Coro di Lecce. Nella Stagione Lirica Leccese \u00e8 stata la Contessa di Ceprano nel Rigoletto di Verdi con la Regia di Vittorio Sgarbi e la Nella in Gianni Schicchi di Puccini, regia Mario Corradi.<br \/>\n<strong>Luisella De Pietro (Santuzza, Cavalleria Rusticana)<\/strong><\/p>\n<p>Soprano, ha intrapreso lo studio del canto sotto la guida del M\u00b0 Mario Canan\u00e0 Si \u00e8 diplomata col massimo dei voti presso il Conservatorio \u201cn. Piccinni\u201d di Bari. Ha interpretato con grande successo i ruoli principali de \u201cLa Traviata\u201d (Violetta Valery), \u201cIl Trovatore\u201d (Leonora), \u201cAida\u201d (Aida) \u201cOtello\u201d (Desdemona) di G. Verdi; ne \u201cLa Boh\u00e8me\u201d (Mim\u00ec), \u201cTurandot\u201d (Li\u00f9 ) di G. Puccini, \u201cTosca\u201d (Floria Tosca) \u201cMadama Butterfly\u201d (Cio Cio San), \u201cSuor Angelica\u201d (Angelica), \u201cDon Giovanni\u201d (Donna Anna \u2013 Donna Elvira) \u201cnozze di Figaro\u201d (Contessa) di W. A. Mozart, \u201cnorma\u201d (norma) di V. Bellini. \u201celisir d\u2019Amore\u201d (Adina) di G. Donizetti, \u201cPagliacci\u201d (nedda) di R. Leoncavallo, \u201cLa Vedova Allegra\u201d (Anna Glavari) di F. Lehar, \u201cCarmen\u201d (Micaela) di Bizet. \u201cnabucco\u201d (Abigaille) di G. Verdi. \u201cUn ballo in maschera\u201d (Amelia) di G. Verdi. Si \u00e8 esibita in diversi teatri italiani ed esteri, tra i quali: Teatro Regio di Parma, Teatro \u201cG.Verdi\u201d di Busseto, Teatro \u201cF.P. Tosti\u201d di ortona, Teatro \u201cMarruccino\u201d di Chieti , Teatro delle Logge di Montecosaro, Teatro \u201cT. Traetta\u201d di Bitonto, Teatro \u201cG. Rossini\u201d di Gioia del Colle, Teatro \u201cCurci\u201d di Barletta, Teatro \u201cG. Verdi\u201d di San Severo, Palazzo Ducale di Martina Franca, Teatro di Stato di Stettino (Polonia) Teatro \u201cG. Paisiello\u201d di Lecce, Madrid Theatre di Kansas City, Theatre Koninklijke Schouwburg di Den Haag, Teatro Capitole di Gent, Luxor Theatre di Rotterdam, Theatre Stadsschouwburg di Utrecht, Parktheater di eindhoven, Theatre di oostende, Stadssc.<br \/>\n<strong>Antonella Colaianni (Paggio, Zanetto; Lola, Cavalleria Rusticana)<\/strong><\/p>\n<p>Si avvicina giovanissima allo studio della musica come strumentista, flautista, ha raggiunto ottimi risultati che l&#8217;hanno portata a esibirsi come strumento solista in diverse manifestazioni. Nel 2002 intraprende lo studio del canto lirico. Si \u00e8 formata presso il Conservatorio &#8220;T. Schipa&#8221; di Lecce sotto la guida del M. Maurizio Picconi e ha seguito i corsi di Musica Vocale da Camera con la M. Amelia Felle. Consegue il diploma in canto nel 2009 col massimo dei voti e la lode. Si perfeziona col M\u00b0 Sherman Lowe. Nel 2010 \u00e8 vincitrice del 64\u00b0 concorso lirico \u201cA. Belli\u201d per giovani cantanti lirici di Spoleto aggiudicandosi il premio speciale \u201cLivia Dionisi\u201d. Ha seguito master con artisti di fama come Luigi Alva, Renato Bruson, Norma Fantini, Enza Ferrari, Carlo Palleschi, Giorgio Bongiovanni, Alessio Pizzech, Marco Ruggieri.<br \/>\n<strong>Angelo Villari (Turiddu, Cavalleria Rusticana)<\/strong><\/p>\n<p>Nato a Messina, ha conseguito il diploma in canto lirico presso il conservatorio &#8220;A. Boito&#8221; di Parma. Ammesso al corso internazionale di formazione &#8220;G.Verdi e II canto solista&#8221; tenuto dalla Fondazione A. Toscanini di Parma nell&#8217;a.a. 2003-04, ha avuto modo di perfezionare la tecnica vocale e interpretativa con il M\u00b0 Alain Charles Billard. Ha debuttato in opere quali : &#8220;Il Filosofo di Campagna&#8221; di B.Galuppi ; &#8221; L&#8217;oca del cairo &#8221; di W.A.Mozart ; &#8221; Le convenienze e le inconvenienze teatrali &#8220;ed &#8220;Il Mos\u00e8 in Egitto&#8221; di G. Rossini. Vincitore del 1\u00b0 Premio al Concorso Internazionale &#8220;Vincenzo Bellini&#8221; di Caltanissetta nel 2009 e del 10 Premio al Concorso Internazionale di canto&#8221; Simone Alaimo, Il bel canto&#8221; nel 2010.<br \/>\n<strong>Giuseppe Altomare (Alfio, Cavalleria Rusticana)<\/strong><\/p>\n<p>Ha iniziato i suoi studi musicali presso la \u201c Hochschule Mozartem\u201d di Salisburgo. Il suo debutto assoluto \u00e8 stato nel ruolo di Gianni Schicchi al 39\u00b0 Festival Puccini di Torre del Lago con la regia del M\u00b0 Rolando Panerai e la direzione del M\u00b0 Marcello Panni. I principali teatri in cui si \u00e8 esibito sono: Festival Puccini di Torre del Lago; Gran Guardia di Livorno; Giglio di Lucca; Comunale di Ferrara; \u201cD. Alighieri\u201d di Ravenna; Comunale di Modena; Tonhalle di D\u00fcsseldorf; Massimo di Palermo; Regio di Parma; Baltimore Opera dCompany, \u201cP. L. da Palestrina\u201d di Cagliari; Pittsburgh Opera; Opernhaus di Zurigo; Comunale di Bologna; National Concert Hall di Dublino; Auditorium Orchestra \u201cVerdi\u201d di Milano; Maggio Musicale Fiorentino; Macerata Opera; Opera di Roma; Teatro Carlo Felice di Genova; Teatro alla Scala; Teatro del Cremlino; Teatro La Fenice. Ha collaborato ancora col M\u00b0 Pierluigi Pizzi nel ruolo di Germont ne La Traviata tenutasi al Teatro Sejong di Seoul riscuotendo un grandissimo successo. E&#8217; stato ancora Rigoletto come cover del M\u00b0 Leo Nucci e sotto la bacchetta del M\u00b0 Daniel Oren. Ha avuto il suo grande debutto al Teatro La Fenice nel ruolo di Scarpia accanto a colleghi come D. Dess\u00ec, F. Armiliato e W. Fraccaro.<br \/>\n<strong>Marinella Rizzo (Mamma Lucia, Cavalleria Rusticana)<\/strong><\/p>\n<p>Mezzosoprano, si \u00e8 diplomata in canto lirico e barocco presso il conservatorio \u201cT.Schipa\u201d di Lecce con il massimo dei voti. Ha proseguito il percorso di formazione vocale e repertorio con il soprano Margherita Rinaldi, il maestro Valentino Barcellesi, il maestro Michael Aspinall. Attualmente \u00e8 seguita dal maestro Sherman Lowe e frequenta il biennio di Canto Barocco presso il Conservatorio \u201cT.Schipa\u201d di Lecce. Ruoli debuttati: Eugenia ne\u201cIl filosofo di campagna\u201ddi Baldassarre Galuppi; Serpina ne\u201cIl barone di Torreforte\u201d di N. Piccinni; Lola nella \u201cCavalleria Rusticana\u201d di P. Mascagni; Kate Pinkerton in \u201cMadama Butterfly\u201d di Giacomo Puccini; Hilaria nella prima mondiale dI \u201cDer Misogyne \u201c di H.W. Plate presso il Theater Wolfsburg ed il\u00a0 Lessingtheater di Wolfenbuttel in Germania.<br \/>\n<strong>REGISTA<br \/>\n<\/strong><strong>Michele Mirabella<br \/>\n<\/strong>E&#8217; tra i pi\u00f9 poliedrici e versatili uomini di cultura e di spettacolo del panorama italiano.\u2028Autore ed attore di teatro, cinema, radio e televisione, regista e sceneggiatore, docente, saggista e giornalista, laureato cum laude in Lettere e Filosofia con uno studio di regia sul teatro di Pirandello nonch\u00e9, ad honorem, in Farmacia, \u00e8 Docente di Sociologia della Comunicazione presso l\u2019Universit\u00e0 di Bari ed ha tenuto corsi su varianti dello stesso tema presso gli Atenei \u00a0di Viterbo, Lecce, Siena, Urbino,Brescia ed alla IULM di Milano. Ha tenuto seminari sul linguaggio teatrale e sulla commedia dell\u2019arte presso \u00a0L\u2019Academy of Dramatic Art di New York. E\u2019 Sovrintendente e Direttore Artistico dei teatri di Udine e di Bitonto, Consigliere d\u2019amministrazione della Fondazione Petruzzelli di Bari e dell\u2019Auditorium del Parco della Musica di Roma, Presidente del Consiglio d\u2019amministrazione dell\u2019Accademia di Belle Arti di Bari. E\u2019 Commendatore dell\u2019Ordine al Merito della Repubblica Italiana. Lavora in Rai dal 1973 quale regista, autore e conduttore di programmi con gran successo di critica e di pubblico quali il celeberrimo \u201cElisir\u201d giunto oltre la 270\u00b0 puntata, premiati con prestigiosi riconoscimenti quali il\u201d Microfono d\u2019argento\u201d, la \u201cMaschera d\u2019argento\u201d, il premio \u201cNaxos\u201d e, per ben due volte, il \u201cTelegatto\u201d. Per il teatro di prosa ha firmato la regia di oltre cinquanta spettacoli presso compagnie Teatrali primarie, sperimentali e Teatri Stabili quali La compagnia del Teatro Popolare di Bari, gli Stabili di Roma e di Torino, il Teatro Greco di Siracusa, il Teatro Sud, il Teatro dell\u2019Orologio di Roma, mettendo in scena opere di Aristofane, Plauto, Goldoni, Brecht, Shakespeare, Pirandello, Ruzante, Alberti, Shisgall, Mrozek, Benni. Ha lavorato per il cinema (circa trenta film) e per la pubblicit\u00e0 come regista, sceneggiatore e \u00a0attore. E\u2019 evidente che una simile personalit\u00e0 non poteva esimersi dal cedere alla sirena del Melodramma, sua grande passione; lo prova l\u2019assidua presenza, in qualit\u00e0 di regista, in teatri e festivals mettendo in scena titoli quali Il barbiere di Siviglia, L&#8217;elisir d\u2019amore, Don Pasquale, Lucia di Lammermore, LaTraviata, Butterfly, Tosca, Manon Lescaut, nonch\u00e9 la sua collaborazione con il \u201cCentro studi musicali Tommaso Traetta\u201d di Bitonto per la riscoperta e messa in scena delle opere Le serve rivali e Il cavaliere errante.<br \/>\n<strong>MAESTRO CONCERTATORE E DIRETTORE D\u2019ORCHESTRA<br \/>\n<\/strong><strong>Paolo Olmi<br \/>\n<\/strong>Nato a Terni ma sempre vissuto a Ravenna si \u00e8 dedicato allo studio della direzione d\u2019orchestra prima con Franco Ferrara poi con Massimo Pradella. Giovanissimo ha iniziato a dirigere sia in Italia che all\u2019estero e da allora la sua carriera \u00e8 stata sempre in crescendo. Grande conoscitore di opere fin da bambino grazie alla passione di famiglia, si \u00e8 dedicato fin da subito oltre che alla musica sinfonica alla direzione di opere liriche, e il suo repertorio \u00e8 oggi vastissimo: comprende tutte le opere di Verdi da Jerusalem e Falstaff (diretti recentemente al Concertgebouw di Amsterdam) a Otello, passando per Ernani, Nabucco,Trovatore, Traviata, Rigoletto, Vespri Siciliani, Don Carlos, Aida, La Forza del Destino, Un ballo in Maschera, molto Rossini sia buffo (Barbiere di Siviglia, Gazza Ladra) che serio (L\u2019Assedio di Corinto, Guglielmo Tell, Mos\u00e8), Puccini (Boheme, Tosca, Manon Lescaut, Fanciulla del West, Madama Butterfly,Turandot), Ponchielli (La Gioconda), Giordano (Andrea Chenier) ma anche Donizetti sia buffo che serio (Don Pasquale, Elisir d\u2019Amore, Anna Bolena, Maria Stuarda, Lucia di Lammermoor), Bellini (La Sonnambula, Zaira) e Mozart (Nozze di Figaro, Cos\u00ec fan Tutte, Flauto Magico) Cilea (Adriana Lecouvreur), Gounod (Romeo e Juliette), Kurt Weil (Ascesa e caduta della citt\u00e0 di Mahagonny). Dedito con passione alla musica sacra (Requiem di Verdi, di Mozart, di Faur\u00e8, Petite Messe Solemnelle di Rossini e Stabat Mater di Rossini ma anche di Pergolesi, Missa Solemnis di Beethoven) che ama molto dirigere nelle chiese, \u00e8 anche appassionato di voci e di canto e moltissimi giovani cantanti hanno iniziato la loro carriera con i consigli di Olmi,che ha avuto il piacere di dirigere e di essere stimato da tantissimi grandi solisti, vecchi e giovani, di tutti i tipi di strumento. Ha diretto solamente grandi orchestre e solamente in teatri importanti , per citare alcuni l\u2019Opera di Roma, la Fenice di Venezia, il Regio di Torino, il Comunale di Bologna, il Carlo Felice di Genova, la Staatsoper di Monaco di Baviera, la Deutsche Oper di Berlino, l\u2019Opera di Chicago,il Teatro Real di Madrid, il Teatro degli Champs Elisees di Parigi, il Liceu di Barcellona, il Covent Garden, la Royal Festival Hall e il Barbican di Londra, il Colon di Buenos Aires , il New National Theatre di Tokyo, l\u2019Opera di Dresda,l\u2019 Arena di Verona, Santa Cecilia di Roma, la Scala (in un concerto nel 1986 con Rostropovich), la Philharmonie di Berlino, Concertgebow di Amsterdam e recentemente l\u2019Opera Canadese di Toronto. Ha inaugurato il nuovo Teatro di Shanghai nel 1998, e ha diretto molte volte in Cina, paese che lo appassiona molto, fin dal 1987, primo fra gli italiani, fino agli anni pi\u00f9 recenti, a Pechino, Shanghai, Macao e Hong Kong. Dal 2001 tiene ogni anno, unico italiano, una master class presso la Guildhall School of Musica and Drama di Londra, una delle istituzioni musicali pi\u00f9 prestigiose al mondo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/pietro-mascagni-zanetto-cavalleria-rusticana\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/pietro-mascagni-zanetto-cavalleria-rusticana\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 8 Febbraio 2013, ore 20,45 \u00a0&#8211; \u00a0Domenica 10 Febbraio 2013, ore 18.00 \u00a0&#8211;\u00a0Teatro Politema Greco di Lecce Puntuale ad un appuntamento prestigioso ed atteso, anche quest\u2019anno la tradizionale Stagione Lirica, la 44esima, richiama chi crede alla bellezza ed alla grandezza della musica. Bellezza e grandezza che sono in special modo della nostra fulgida tradizione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10545,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10544"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10544"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10544\/revisions"}],"predecessor-version":[{"id":10547,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10544\/revisions\/10547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10545"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}