{"id":10555,"date":"2013-02-07T08:00:09","date_gmt":"2013-02-07T08:00:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10555"},"modified":"2013-02-07T08:01:17","modified_gmt":"2013-02-07T08:01:17","slug":"riparte-improvvisa-sul-palcoscenico-oggi-giovedi-7-febbraio-la-presentazione","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/riparte-improvvisa-sul-palcoscenico-oggi-giovedi-7-febbraio-la-presentazione\/","title":{"rendered":"RIPARTE IMPROVVISA SUL PALCOSCENICO &#8211; OGGI GIOVEDI&#8217; 7 FEBBRAIO LA PRESENTAZIONE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/riparte-improvvisa-sul-palcoscenico-oggi-giovedi-7-febbraio-la-presentazione\/maschere\/\" rel=\"attachment wp-att-10556\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/MASCHERE.jpeg\" alt=\"\" width=\"300\" height=\"238\" class=\"alignleft size-full wp-image-10556\" \/><\/a>Gioved\u00ec, 7 febbraio, alle 11.30, a Palazzo Carafa, verr\u00e0 presentata la terza edizione di \u201cImprovviva!\u201d, la rassegna nazionale di Improvvisazione Teatrale<br \/>\nLa rassegna nazionale di Improvvisazione Teatrale giunta oramai alla terza edizione, riparte, e \u00a0pu\u00f2 contare sui\u00a0 migliori attori professionisti tutti appartenenti ad Improteatro, il pi\u00f9 grande circuito di Improvvisazione Teatrale italiano.<br \/>\nLa rassegna &#8211; patrocinata dal Comune di Lecce (Assessorato alla Cultura, Turismo e Spettacolo) e dalla Regione Puglia e che pu\u00f2 contare sul supporto di ADISU Puglia &#8211; \u00a0si compone di quattro appuntamenti che da febbraio a maggio porteranno a Lecce i format pi\u00f9 famosi dell&#8217;Improvvisazione Teatrale.<br \/>\nL\u2019evento verr\u00e0 presentato gioved\u00ec 7 febbraio, alle ore 11.30, nella sala giunta di Palazzo Carafa, alla presenza dell\u2019assessore agli Spettacoli e Agli Eventi, Luigi Coclite, del presidente e della vicepresidente della cooperativa Improvvisart, Fabio Musci e Alessandra Villa.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/riparte-improvvisa-sul-palcoscenico-oggi-giovedi-7-febbraio-la-presentazione\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/riparte-improvvisa-sul-palcoscenico-oggi-giovedi-7-febbraio-la-presentazione\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec, 7 febbraio, alle 11.30, a Palazzo Carafa, verr\u00e0 presentata la terza edizione di \u201cImprovviva!\u201d, la rassegna nazionale di Improvvisazione Teatrale La rassegna nazionale di Improvvisazione Teatrale giunta oramai alla terza edizione, riparte, e \u00a0pu\u00f2 contare sui\u00a0 migliori attori professionisti tutti appartenenti ad Improteatro, il pi\u00f9 grande circuito di Improvvisazione Teatrale italiano. La rassegna &#8211; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10556,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10555"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10555"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10555\/revisions"}],"predecessor-version":[{"id":10561,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10555\/revisions\/10561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10556"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}