{"id":10568,"date":"2013-02-07T08:16:57","date_gmt":"2013-02-07T08:16:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10568"},"modified":"2013-02-07T08:16:57","modified_gmt":"2013-02-07T08:16:57","slug":"lecce-capitale-della-cultura","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/lecce-capitale-della-cultura\/","title":{"rendered":"LECCE CAPITALE DELLA CULTURA"},"content":{"rendered":"<p><em><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/lecce-capitale-della-cultura\/capitale-europea-dei-giovani-2015\/\" rel=\"attachment wp-att-10569\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/capitale-europea-dei-giovani-2015.jpg\" alt=\"\" width=\"271\" height=\"238\" class=\"alignleft size-full wp-image-10569\" \/><\/a>L\u2019assessore alle Politiche comunitarie e all&#8217;Innovazione tecnologica, Alessandro Delli Noci, \u00e8 intervenuto questa mattina alla\u00a0 conferenza Smau di Bari, evento fieristico dedicato alla tecnologia e al mondo dell&#8217;informatica, per sottolineare il percorso, intrapreso ormai da mesi dalla citt\u00e0 di Lecce \u201cverso obiettivi importanti in seno allo sviluppo tecnologico e, pi\u00f9 in generale, socio-culturale\u201d<\/em><\/p>\n<p>\u201cLe interessanti sollecitazioni che stanno emergendo dai tavoli di lavoro che stiamo portando avanti in queste settimane stanno rafforzando la mia convinzione secondo cui i progetti \u201cSmart city\u201d e \u201cLecce capitale della cultura\u201d siano tra loro contigui, complementari e persino, in molti casi, sovrapponibili, nella misura in cui sono mossi, entrambi, dalla propulsione del processo creativo.\u00a0 A tal proposito, mi piace ricordare la definizione del matematico e fisico francese Henri Poincar\u00e9, uno dei padri della fortunata teoria della complessit\u00e0, che parla della creativit\u00e0 come della \u201ccapacit\u00e0 di unire tra loro elementi generando combinazioni nuove, utili, laddove il criterio per riconoscerne l\u2019utilit\u00e0 \u00e8 nell\u2019essere armonica, funzionale allo scopo, costruttiva.<\/p>\n<p>Sar\u00f2 un visionario, ma all\u2019interno di questa definizione, mi appare, chiara ed evidente, la stretta relazione tra creativit\u00e0, tecnologia e cultura. Parafrasando Poincar\u00e8, potrei dire che se l\u2019innovazione tecnologica nelle citt\u00e0 \u00e8 supportata da processi creativi, oltre che garantire nuovi strumenti e servizi ai cittadini, generer\u00e0 anche combinazioni utili (e quindi armoniche, funzionali e costruttive) allo sviluppo culturale della societ\u00e0. In sintesi, una citt\u00e0 permeata dalla tecnologia non pu\u00f2 definirsi \u201csmart\u201d, a meno che non sviluppi anche un\u2019economia della conoscenza, ovvero che non consenta ai propri cittadini di migliorare la qualit\u00e0 delle proprie vite. E solo una citt\u00e0 creativa pu\u00f2 prepararsi veramente al futuro, diventando un laboratorio in cui si elaborano idee intelligenti di cambiamento, di innovazione, di evoluzione culturale.<\/p>\n<p>Uno dei cambiamenti forse pi\u00f9 promettenti dell\u2019era digitale \u00e8 la trasformazione stessa delle citt\u00e0. Smesse le vesti di contenitore fisico di strutture, di abitazioni, di strade, di persone, il villaggio \u2013 non a caso definito \u201cglobale\u201d da M. Mc Luhan \u2013 si dematerializza per diventare percorso, incontro, passaggio di esperienze e di conoscenze, di emozioni e di sensazioni. La rete stradale non \u00e8 altro che una metafora delle possibili congiunzioni tra gli individui che internet e le nuove tecnologie hanno reso istantanee e una citt\u00e0 diventa smart quando \u00e8 orientata e sostenuta da processi creativi e da politiche per lo sviluppo, in termini di efficacia e di efficienza, di queste connessioni.<\/p>\n<p>Considerare un progetto per le \u201csmart cities\u201d come semplice operazione di restyling degli spazi cittadini o di risparmio economico per le amministrazioni comunali \u00e8 fuorviante, limitante, oltre che imprevidente. E Lecce non si muove in questa direzione. Nella propria candidatura a Capitale della Cultura e nell\u2019adesione al progetto \u201cSmart Cities\u201d, la nostra citt\u00e0 ha l\u2019ambizione di promuoversi come luogo della comunicazione e fucina della creativit\u00e0 giovanile ed imprenditoriale, come opportunit\u00e0 per i propri cittadini. \u00c8 questa l&#8217;idea nella quale il mio Assessorato si identifica, \u00e8 questo il percorso che intende portare avanti, attraverso il sostegno e l\u2019incentivazione di progetti creativi, come baluardo per uno sviluppo non solo digitale, ma, soprattutto, culturale<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/lecce-capitale-della-cultura\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/lecce-capitale-della-cultura\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>L\u2019assessore alle Politiche comunitarie e all&#8217;Innovazione tecnologica, Alessandro Delli Noci, \u00e8 intervenuto questa mattina alla\u00a0 conferenza Smau di Bari, evento fieristico dedicato alla tecnologia e al mondo dell&#8217;informatica, per sottolineare il percorso, intrapreso ormai da mesi dalla citt\u00e0 di Lecce \u201cverso obiettivi importanti in seno allo sviluppo tecnologico e, pi\u00f9 in generale, socio-culturale\u201d \u201cLe interessanti [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10569,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10568"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10568"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10568\/revisions"}],"predecessor-version":[{"id":10572,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10568\/revisions\/10572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10569"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}