{"id":106216,"date":"2016-12-22T13:20:48","date_gmt":"2016-12-22T12:20:48","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=106216"},"modified":"2016-12-22T13:37:30","modified_gmt":"2016-12-22T12:37:30","slug":"brevi-di-cronaca-nera-23","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/12\/22\/brevi-di-cronaca-nera-23\/","title":{"rendered":"BREVI DI CRONACA NERA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" title=\"IMG-20161222-WA0004\" class=\"aligncenter size-medium wp-image-106223\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/IMG-20161222-WA0004-300x168.jpg\" \/>Avetrana. A un imprenditore di Avetrana, titolare di un&#8217;\u00a0impresa per l&#8217; estrazione di materiale di costruzione, in una cava di Fragagnano, la Guardia di Finanza ha sequestrato questa mattina beni mobili e immobili per circa un milione di euro. Il provvedimento, emesso dal Tribunale di Taranto, \u00e8 di importo pari alle imposte che, secondo l&#8217; accusa, l&#8217; uomo ha evaso dal \u00a02007 al 2012.<\/p>\n<p>&nbsp;<\/p>\n<p>Taranto. Un uomo di 50 anni \u00e8 stato arrestato e posto ai domiciliari con l&#8217; accusa di atti persecutori nel confronti della sua ex compagna. Anche al Tribunale di Taranto seguono la linea dura nei confronti dei responsabili di stalking. Secondo le indagini compiute dalla Polizia di Stato da oltre un anno l&#8217; uomo molestava la donna, dopo la fine della loro relazione, incurante della presenza della figlia piccola, seguendola, telefonandole ripetutamente,\u00a0messaggiandola sui social network, bussando al citofono di casa e addirittura tracciando con lo spray scritte sui muri del quartiere.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/12\/22\/brevi-di-cronaca-nera-23\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/12\/22\/brevi-di-cronaca-nera-23\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Avetrana. A un imprenditore di Avetrana, titolare di un&#8217;\u00a0impresa per l&#8217; estrazione di materiale di costruzione, in una cava di Fragagnano, la Guardia di Finanza ha sequestrato questa mattina beni mobili e immobili per circa un milione di euro. Il provvedimento, emesso dal Tribunale di Taranto, \u00e8 di importo pari alle imposte che, secondo l&#8217; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":106223,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/106216"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=106216"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/106216\/revisions"}],"predecessor-version":[{"id":106227,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/106216\/revisions\/106227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/106223"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=106216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=106216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=106216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}