{"id":106255,"date":"2016-12-22T17:59:19","date_gmt":"2016-12-22T16:59:19","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=106255"},"modified":"2016-12-22T18:00:17","modified_gmt":"2016-12-22T17:00:17","slug":"massacra-di-botte-un-suo-connazionale-romeno-arrestato-a-mesagne-per-tentato-omicidio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/12\/22\/massacra-di-botte-un-suo-connazionale-romeno-arrestato-a-mesagne-per-tentato-omicidio\/","title":{"rendered":"MASSACRA DI BOTTE UN SUO CONNAZIONALE, ROMENO ARRESTATO A MESAGNE PER TENTATO OMICIDIO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"216\" height=\"300\" title=\"RI\" class=\"aligncenter size-medium wp-image-106256\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/RI2-216x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/RI2-216x300.jpg 216w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/RI2-737x1024.jpg 737w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/RI2-768x1066.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/RI2-1106x1536.jpg 1106w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/12\/RI2.jpg 1374w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/>(e.l.)______Grave episodio di violenza ieri sera nella comunit\u00e0 romena di Mesagne. E&#8217; stato proprio uno di loro a recarsi in commissariato e ad allertare i poliziotti, riferendo quanto era appena successo, nella speranza di evitare il peggio.<\/p>\n<p>Quando gli agenti della Polizia di Stato sono arrivati nell&#8217; abitazione loro indicata sulla strada provinciale per San Pietro Vernotico, hanno ricostruito l&#8217; ccaduto e arrestato il responsabile.<\/p>\n<p>Si tratta di Nicolae Alexandru (nella foto), 49 anni, pregiudicato, che, probabilmente in preda ai fumi dell&#8217; alcool, ha aggredito il suo connazionale Ilie Doroftei,\u00a0colpendolo con calci e pugni, anche quando era riverso per terra, e utilizzando pure\u00a0un\u2019ascia.<\/p>\n<p>La vittima, soccorsa dai sanitari del 118, \u00e8 stata portata all&#8217;\u00a0ospedale \u201cPerrino\u201d di Brindisi, dove, attualmente, si trova ricoverata in prognosi riservata, avendo riportato un trauma cranico e numerose fratture; le sue condizioni, apparse subito molto gravi, continuano ad essere critiche.<\/p>\n<p>L\u2019autore della violenta aggressione, invece, su disposizione del pubblico ministero di turno, Manuela Pellerino,\u00a0\u00e8 stato arrestato, e condotto presso la Casa Circondariale di Brindisi.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/12\/22\/massacra-di-botte-un-suo-connazionale-romeno-arrestato-a-mesagne-per-tentato-omicidio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/12\/22\/massacra-di-botte-un-suo-connazionale-romeno-arrestato-a-mesagne-per-tentato-omicidio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Grave episodio di violenza ieri sera nella comunit\u00e0 romena di Mesagne. E&#8217; stato proprio uno di loro a recarsi in commissariato e ad allertare i poliziotti, riferendo quanto era appena successo, nella speranza di evitare il peggio. Quando gli agenti della Polizia di Stato sono arrivati nell&#8217; abitazione loro indicata sulla strada provinciale per San [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":106256,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/106255"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=106255"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/106255\/revisions"}],"predecessor-version":[{"id":106258,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/106255\/revisions\/106258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/106256"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=106255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=106255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=106255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}