{"id":10628,"date":"2013-02-07T19:32:20","date_gmt":"2013-02-07T19:32:20","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10628"},"modified":"2013-02-07T19:32:20","modified_gmt":"2013-02-07T19:32:20","slug":"lavvocato-leccese-francesco-dagata-a-ballaro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/lavvocato-leccese-francesco-dagata-a-ballaro\/","title":{"rendered":"L&#8217;AVVOCATO LECCESE FRANCESCO D&#8217;AGATA A BALLARO&#8217;"},"content":{"rendered":"<div>\n<div>\n<div>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/lavvocato-leccese-francesco-dagata-a-ballaro\/crozza\/\" rel=\"attachment wp-att-10629\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/CROZZA.jpeg\" alt=\"\" width=\"275\" height=\"183\" class=\"alignleft size-full wp-image-10629\" \/><\/a>Dopo aver denunciato per primi la mannaia voluta dal Comune di Lecce per l&#8217;aggiornamento degli estimi catastali cui hanno fatto seguito migliaia di atti di accertamento dell&#8217;Agenzia del Territorio ad altrettanti cittadini, lo Sportello dei Diritti, per il tramite del portavoce nazionale avv. Francesco D&#8217;Agata \u00e9 stato contattato dalla redazione del noto talk\u00a0 politico di Raitre&#8221;, Ballar\u00f2, per il clamore e la rilevanza nazionale suscitata dalla procedura attivata dal comune di Lecce, unico, al momento, in Italia.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">La troupe di Ballar\u00f2 si \u00e9 dunque recata a Lecce e su segnalazione dello stesso socio fondatore dell&#8217;associazione ha intervistato alcuni cittadini ed il noto tributarista avvocato Maurizio Villani che per primo ha segnalato allo Sportello dei Diritti le gravi conseguenze di un procedimento ritenuto illegittimo e che graver\u00e0, e non poco, sulle tasche dei cittadini leccesi proprietari di immobili.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Domenica sera e non marted\u00ec, in quanto \u00e9 stato appena cambiato il palinsesto Rai, Giovanni D&#8217;Agata, invita a tenere gli occhi puntati su Raitre e sulla trasmissione Ballar\u00f2 per ascoltare le testimonianze su di una vicenda tutta italiana che paventa conseguenze di vera e propria iniquit\u00e0 fiscale in capo ai cittadini gi\u00e0 enormemente vessati dal peso di un Fisco divenuto insostenibile.<\/span><\/p>\n<p><span style=\"font-family: Arial;font-size: x-small\">\u00a0<\/span><\/p>\n<div><span style=\"font-family: Arial;font-size: x-small\"><br \/>\n<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/lavvocato-leccese-francesco-dagata-a-ballaro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/07\/lavvocato-leccese-francesco-dagata-a-ballaro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Dopo aver denunciato per primi la mannaia voluta dal Comune di Lecce per l&#8217;aggiornamento degli estimi catastali cui hanno fatto seguito migliaia di atti di accertamento dell&#8217;Agenzia del Territorio ad altrettanti cittadini, lo Sportello dei Diritti, per il tramite del portavoce nazionale avv. Francesco D&#8217;Agata \u00e9 stato contattato dalla redazione del noto talk\u00a0 politico di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10629,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10628"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10628"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10628\/revisions"}],"predecessor-version":[{"id":10632,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10628\/revisions\/10632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10629"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}