{"id":10771,"date":"2013-02-10T12:11:41","date_gmt":"2013-02-10T12:11:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10771"},"modified":"2013-02-10T12:14:06","modified_gmt":"2013-02-10T12:14:06","slug":"firma-dellaccordo-in-campidoglio-per-la-costituzione-della-casa-del-ricordo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/10\/firma-dellaccordo-in-campidoglio-per-la-costituzione-della-casa-del-ricordo\/","title":{"rendered":"Firma dell\u2019accordo in Campidoglio per la costituzione della Casa del Ricordo"},"content":{"rendered":"<p>Il \u201cComitato 10 febbraio\u201d esprime la propria soddisfazione per la firma di un protocollo d\u2019intesa tra il Comune di Roma e le associazioni d\u2019esuli per la realizzazione della Casa del Ricordo.<\/p>\n<div>Un atto dovuto e necessario che rappresenta il risultato di 60 anni d\u2019impegno infaticabile degli esuli e dei parenti delle vittime di una tragedia italiana.<\/div>\n<div>Ancora c\u2019\u00e8 molto da fare ma oggi possiamo brindare ad un buon risultato raggiunto.<\/div>\n<p>\u201cSar\u00e0 firmato in Campidoglio, venerd\u00ec 1\u00b0 febbraio alle ore 15.00, tra Roma Capitale, l\u2019Associazione Nazionale Venezia Giulia e Dalmazia e la Societ\u00e0 di Studi Fiumani \u2013 Archivio Museo Storico di Fiume, il protocollo d\u2019intesa per la costituzione della \u00abCasa del Ricordo\u00bb<strong>\u00a0<\/strong>dell\u2019esodo degli italiani da Istria, Fiume e Zara nel secondo dopoguerra e degli eccidi delle Foibe.<\/p>\n<p>La firma, che avr\u00e0 luogo nella cornice della solenne celebrazione del Giorno del Ricordo nell\u2019Aula Giulio Cesare, giunge a conclusione di un lungo e intenso lavoro condotto con passione, determinazione e grande impegno nel volontariato, dai membri delle associazioni rappresentative degli esuli.<\/p>\n<p>La sigla del protocollo di intesa si colloca nella direzione della conservazione e della divulgazione della storia di quei territori, ceduti alla Jugoslavia di Tito con il trattato di pace del 1947 dopo aver conosciuto le feroci persecuzioni delle milizie jugoslave volte ad indurre la popolazione autoctona alla dolorosa scelta dell\u2019esilio nella Madrepatria.<\/p>\n<p>Il Sindaco di Roma Capitale, Giovanni Alemanno, e il Presidente del Comitato Provinciale di Roma dell\u2019Associazione Nazionale Venezia Giulia e Dalmazia, Donatella Sch\u00fcrzel, anche a nome del Presidente nazionale Antonio Ballarin, sigleranno dunque il documento che sancisce il pieno riconoscimento dei valori di memoria e di ideali che le associazioni per lunghi decenni hanno avuto cura di conservare nonostante il diffuso oblio cui vennero condannati per ingiustificate pregiudiziali ideologiche e circostanze internazionali.<\/p>\n<p>La cerimonia avr\u00e0 pertanto luogo in Roma, nell\u2019Aula Giulio Cesare del Campidoglio, con inizio alle ore 15.00, alla presenza delle pi\u00f9 alte autorit\u00e0 civili e militari. Per info e conferma presenza:\u00a0<a href=\"06.6710.4934\" target=\"_blank\">06.6710.4934<\/a>\/4940 \/4942 o\u00a0<a href=\"mailto:cerimoniale.romacapitale@comune.roma.it\" target=\"_blank\">cerimoniale.romacapitale@comune.roma.it<\/a>\u00a0entro le ore 14.50 del 1\u00b0 febbraio.<\/p>\n<header>\n<h2><\/h2>\n<\/header>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/10\/firma-dellaccordo-in-campidoglio-per-la-costituzione-della-casa-del-ricordo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/10\/firma-dellaccordo-in-campidoglio-per-la-costituzione-della-casa-del-ricordo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il \u201cComitato 10 febbraio\u201d esprime la propria soddisfazione per la firma di un protocollo d\u2019intesa tra il Comune di Roma e le associazioni d\u2019esuli per la realizzazione della Casa del Ricordo. Un atto dovuto e necessario che rappresenta il risultato di 60 anni d\u2019impegno infaticabile degli esuli e dei parenti delle vittime di una tragedia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10771"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10771"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10771\/revisions"}],"predecessor-version":[{"id":10774,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10771\/revisions\/10774"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}