{"id":10893,"date":"2013-02-13T11:58:25","date_gmt":"2013-02-13T11:58:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10893"},"modified":"2013-02-13T11:58:25","modified_gmt":"2013-02-13T11:58:25","slug":"parte-il-progetto-per-lo-sviluppo-del-turismo-sostenibile","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/13\/parte-il-progetto-per-lo-sviluppo-del-turismo-sostenibile\/","title":{"rendered":"PARTE IL PROGETTO PER LO SVILUPPO DEL TURISMO SOSTENIBILE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><span style=\"text-decoration: underline\">Domani, gioved\u00ec 14 febbraio alle ore 11.30, nella sala consiliare di Palazzo dei Celestini, a Lecce<\/span>, si terr\u00e0 la conferenza stampa di presentazione del progetto europeo \u201c<strong>Live your tour. A cross-border network to increase sound and harmonious tourism in Italy, Spain, Lebanon and Tunisia<\/strong>\u201d, di cui la Provincia di Lecce \u00e8 partner.<br \/>\nL\u2019iniziativa sar\u00e0 illustrata dal presidente della Provincia di Lecce <strong>Antonio Gabellone<\/strong>, dall\u2019assessore provinciale al Turismo e Marketing territoriale <strong>Francesco Pacella <\/strong>e dal presidente di Ricerca e Cooperazione <strong>Arturo Parolini<\/strong>.<br \/>\nL\u2019incontro con i giornalisti avverr\u00e0 al termine del kick off meeting del progetto, in pratica l\u2019avvio ufficiale programmato nella stessa mattinata, sempre nella sala consiliare, con la partecipazione di tutti i rappresentanti coinvolti: <strong>Carmelo Calamia<\/strong>, <strong>Antonio Rizzo<\/strong> e <strong>Stefania Doria<\/strong> per la Provincia di Lecce; <strong>Walid Attallah<\/strong>, coordinatore di Progetto per conto del Programma di Sviluppo delle Nazioni Unite (UNDP) (Libano); <strong>Nouha Ghosseini<\/strong>, presidente della Unione delle Municipalit\u00e0\u00a0 dello Chouf Soueyjani (Libano); <strong>Haytham Nammour<\/strong>, dell\u2019Universit\u00e0 Americana per la Cultura e l\u2019Educazione (Libano); <strong>Yolanda Ramirez<\/strong>, responsabile del Fondo delle Municipalit\u00e0 Andaluse per la Solidariet\u00e0 Internazionale (FAMSI) (Spagna); <strong>Emira Sghaier<\/strong>, Ricerca e Cooperazione (Libano-Italia); <strong>Gabriella Rossi Crespi<\/strong>, Ricerca e Cooperazione (Italia); <strong>Majdi Calboussi<\/strong>, Associazione Tunisina per le Gestione e la Stabilit\u00e0 Sociale (TAMSS) (Tunisia); <strong>Bassam Hariri<\/strong>, Presidente dell\u2019Unione delle Municipalit\u00e0\u00a0 di Baalbeck (Libano); <strong>Alessandro Ciccolella<\/strong>, Consorzio di Gestione di Torre Guaceto (Italia); <strong>Gianfranco Ciola<\/strong>,<strong> <\/strong>Parco Regione delle Dune Costiere da Torre Canne a Torre San Leonardo (Italia); <strong>Silvia Fracchia<\/strong>, Technical Secretariat (Regione Sardegna); <strong>Fabrizio Floris<\/strong> Technical Secretariat (Regione Sardegna).<\/p>\n<p>Finanziato con un budget complessivo di oltre <strong>4 milioni 960 mila euro<\/strong>, nell\u2019ambito del Programma di Cooperazione Territoriale Europea CBC ENPI \u2013 Bacino del Mediterraneo (European Neighbourhood and Partnership Instrument), il progetto \u201c<strong>Live your tour<\/strong>\u201d punta ad incrementare i flussi di turismo sostenibile in alcune aree obiettivo di Italia, Spagna, Libano e Tunisia, favorendo la destagionalizzazione, lo sviluppo di aree geografiche marginali e la valorizzazione delle culture locali.<\/p>\n<p>Partner capofila del progetto \u00e8 Ricerca e Cooperazione ONG, con sede a Roma. Gli altri partner, oltre la Provincia di Lecce, sono l\u2019Associazione no profit per la solidariet\u00e0 internazionale con sede in Andalusia (Spagna), il Consorzio Parco Dune Costiere (Puglia), il Consorzio Parco Torre Guaceto (Puglia), l\u2019Associazione di Studi di management americana ONG in Tunisia (Tunisia), l\u2019Unione di Municipalit\u00e0 di Baalbeck (Libano), la Federazione di Municipalit\u00e0 Chouf Es Souayjani (Libano).<\/p>\n<p>\u201cLive your tour\u201d rientra nel Programma di Cooperazione Territoriale Europea CBC ENPI \u2013 Bacino del Mediterraneo, alla cui elaborazione e presentazione ha partecipato ampiamente anche la Provincia di Lecce. Il Programma \u00e8 stato approvato dalla Commissione dell\u2019Unione Europea il 14 agosto 2008 con l\u2019obiettivo di promuovere una cooperazione armoniosa e sostenibile nel Bacino del Mediterraneo, individuando soluzioni congiunte per sfide comuni, rafforzando il potenziale endogeno dei territori coinvolti e rendendo pi\u00f9 sicuri i confini marittimi mediterranei dell\u2019Unione Europea.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/13\/parte-il-progetto-per-lo-sviluppo-del-turismo-sostenibile\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/13\/parte-il-progetto-per-lo-sviluppo-del-turismo-sostenibile\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Domani, gioved\u00ec 14 febbraio alle ore 11.30, nella sala consiliare di Palazzo dei Celestini, a Lecce, si terr\u00e0 la conferenza stampa di presentazione del progetto europeo \u201cLive your tour. A cross-border network to increase sound and harmonious tourism in Italy, Spain, Lebanon and Tunisia\u201d, di cui la Provincia di Lecce \u00e8 partner. L\u2019iniziativa sar\u00e0 illustrata [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10893"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10893"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10893\/revisions"}],"predecessor-version":[{"id":10894,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10893\/revisions\/10894"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}