{"id":109512,"date":"2017-02-02T00:05:25","date_gmt":"2017-02-01T23:05:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=109512"},"modified":"2017-01-31T15:14:47","modified_gmt":"2017-01-31T14:14:47","slug":"i-nostri-amici-animali-le-storie-di-federica-365","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/02\/02\/i-nostri-amici-animali-le-storie-di-federica-365\/","title":{"rendered":"I NOSTRI AMICI ANIMALI \/ LE STORIE DI FEDERICA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"505\" height=\"378\" title=\"statte-sgravi-fiscali-per-chi-adotta-un-cane--1485868751-grande\" class=\"aligncenter size-full wp-image-109513\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/01\/statte-sgravi-fiscali-per-chi-adotta-un-cane-1485868751-grande.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/01\/statte-sgravi-fiscali-per-chi-adotta-un-cane-1485868751-grande.jpg 505w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/01\/statte-sgravi-fiscali-per-chi-adotta-un-cane-1485868751-grande-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/01\/statte-sgravi-fiscali-per-chi-adotta-un-cane-1485868751-grande-400x300.jpg 400w\" sizes=\"(max-width: 505px) 100vw, 505px\" \/>Evviva Statte!\u00a0Il consiglio comunale, con una deliberazione di marted\u00ec scorso, ha stabilito agevolazioni fiscali per chi adotta un cane in custodia nel canile: Tari dal 50 al 70% in meno ogni anno, per tutta la durata della vita dell&#8217; adottato. Cos\u00ec il presidente della commissione ambiente, Daniele Andrisani ha commentato l&#8217; iniziativa: &#8220;Una scelta economica, ma anche di civilt\u00e0 e sensibilizzazione. Questo regolamento ci mette nelle condizioni di garantire un futuro migliore ai molti cani custoditi all&#8217;interno del canile. In pi\u00f9 l&#8217;ente riduce le spese e prova a dare un segnale di civilt\u00e0 e umanit\u00e0&#8221;.<\/p>\n<p>E l&#8217; ha dato! C&#8217;\u00e8 solo da augurarsi che tanti altri comuni seguano presto il suo esempio virtuoso.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/02\/02\/i-nostri-amici-animali-le-storie-di-federica-365\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/02\/02\/i-nostri-amici-animali-le-storie-di-federica-365\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Evviva Statte!\u00a0Il consiglio comunale, con una deliberazione di marted\u00ec scorso, ha stabilito agevolazioni fiscali per chi adotta un cane in custodia nel canile: Tari dal 50 al 70% in meno ogni anno, per tutta la durata della vita dell&#8217; adottato. Cos\u00ec il presidente della commissione ambiente, Daniele Andrisani ha commentato l&#8217; iniziativa: &#8220;Una scelta economica, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":109513,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[78],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/109512"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=109512"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/109512\/revisions"}],"predecessor-version":[{"id":109514,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/109512\/revisions\/109514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/109513"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=109512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=109512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=109512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}