{"id":10963,"date":"2013-02-15T07:51:45","date_gmt":"2013-02-15T07:51:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=10963"},"modified":"2013-02-15T07:54:11","modified_gmt":"2013-02-15T07:54:11","slug":"donna-muore-per-overdose-di-coca-cola","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/donna-muore-per-overdose-di-coca-cola\/","title":{"rendered":"DONNA MUORE PER &#8220;OVERDOSE&#8221; DI COCA COLA"},"content":{"rendered":"<div>\n<div>\n<div>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/donna-muore-per-overdose-di-coca-cola\/siringa-jpg_415368877\/\" rel=\"attachment wp-att-10964\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/siringa.jpg_415368877.jpg\" alt=\"\" width=\"943\" height=\"296\" class=\"alignleft size-full wp-image-10964\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/siringa.jpg_415368877.jpg 943w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/siringa.jpg_415368877-300x94.jpg 300w\" sizes=\"(max-width: 943px) 100vw, 943px\" \/><\/a>\u00c8 morta per aritmia cardiaca per\u00a0 overdose di Coca Cola dovuta a dipendenza da Coca Cola per una 30enne. Questa la conclusione del coroner, una pesante accusa lanciata dal David Crear, magistrato neozelandese contro il colosso americano della produzione e distribuzione di bevande analcoliche<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Il fatto si riferisce ad una donna di 30 anni che aveva sviluppato dipendenza dalla Coca Cola ed \u00e8 morta per averne bevuta troppa, stroncata da un attacco di aritmia cardiaca.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Secondo i risultati dell&#8217;inchiesta, Natasha Harrish (questo il nome della vittima), beveva giornalmente fino a dieci litri di Coca, il che significa pi\u00f9 del doppio del limite sicuro di caffeina e quasi un chilo di zucchero, oltre che un consumo totale di oltre 24&#8217;000 litri\u00a0in 8 anni.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Nei mesi prima della morte, ha testimoniato il partner, la salute della donna era peggiorata rapidamente. &#8220;Non aveva energia e sentiva nausea tutto il tempo. La mattina si alzava e vomitava&#8221;, ha spiegato l&#8217;uomo, aggiungendo che &#8220;se Natasha non beveva Coca Cola era di cattivo umore, soffriva di emicrania e si sentiva spossata&#8221;.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">\u00a0Nei mesi prima della morte, ha testimoniato il partner Chris Hodgkinson, la salute della donna era rapidamente peggiorata. &#8220;Non aveva energia e sentiva nausea tutto il tempo. La mattina si alzava e vomitava&#8221;. Aveva sviluppato dipendenza: &#8220;se non beveva Coke era di cattivo umore, soffriva di mal di testa e si sentiva priva di energia&#8221;, ha detto.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Secondo i legali della Coca Cola non \u00e8 provato che le grandi quantit\u00e0 della bevanda abbiano contribuito al decesso, poich\u00e9 gli esperti non sono stati concordi sulla sua causa di morte pi\u00f9 probabile. Il coroner David Crerar, in un verdetto destinato ad avere risonanza mondiale, ha invece stabilito che la signora Harris non sarebbe morta se non fosse stato per la dipendenza dalla bevanda. &#8220;Se non fosse stato per il consumo di quantit\u00e0 molto grandi di Coke \u00e8 improbabile che sarebbe morta quando \u00e8 morta e nel modo in cui \u00e8 morta&#8221;, ha detto.<\/span><\/p>\n<p><span style=\"font-family: 'Times New Roman';font-size: small\">Per Giovanni D\u2019Agata, \u00a0auspica anche alla luce di questo ultimo episodio che le autorit\u00e0 competenti considerino di imporre limiti sul contenuto di caffeina e di zucchero nelle bevande effervescenti e l&#8217;apposizione di etichette di avvertimento pi\u00f9 specifiche.<\/span><\/p>\n<div><span style=\"font-family: 'Times New Roman';font-size: small\"><br \/>\n<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/donna-muore-per-overdose-di-coca-cola\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/donna-muore-per-overdose-di-coca-cola\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00c8 morta per aritmia cardiaca per\u00a0 overdose di Coca Cola dovuta a dipendenza da Coca Cola per una 30enne. Questa la conclusione del coroner, una pesante accusa lanciata dal David Crear, magistrato neozelandese contro il colosso americano della produzione e distribuzione di bevande analcoliche Il fatto si riferisce ad una donna di 30 anni che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10964,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10963"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=10963"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10963\/revisions"}],"predecessor-version":[{"id":10969,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/10963\/revisions\/10969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10964"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=10963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=10963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=10963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}