{"id":11054,"date":"2013-02-15T11:46:05","date_gmt":"2013-02-15T11:46:05","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11054"},"modified":"2013-02-15T12:01:00","modified_gmt":"2013-02-15T12:01:00","slug":"siamo-tutti-picchiatori-per-la-cassazione-si","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/siamo-tutti-picchiatori-per-la-cassazione-si\/","title":{"rendered":"SIAMO TUTTI PICCHIATORI? PER LA CASSAZIONE SI"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/siamo-tutti-picchiatori-per-la-cassazione-si\/paolo-borsellino-alemanno-e-granata-alla-festa-nazionale-del-fronte-della-gioventc3b9-di-siracusa-settembre-1990\/\" rel=\"attachment wp-att-11055\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/paolo-borsellino-alemanno-e-granata-alla-festa-nazionale-del-fronte-della-gioventc3b9-di-siracusa-settembre-1990.jpg\" alt=\"\" width=\"720\" height=\"545\" class=\"alignleft size-full wp-image-11055\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/paolo-borsellino-alemanno-e-granata-alla-festa-nazionale-del-fronte-della-gioventc3b9-di-siracusa-settembre-1990.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/paolo-borsellino-alemanno-e-granata-alla-festa-nazionale-del-fronte-della-gioventc3b9-di-siracusa-settembre-1990-300x227.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p>Nellla foto il Giudice Paolo Borsellino, fatto saltare in aria dalla Mafia, l&#8217;attuale Sindaco di Roma Gianni Alemanno, il portavoce FLI Granata, partito del Presidente della Camera Fini.Alla Festa Nazionale del Fronte della Giovent\u00f9 del 1990 a Siracusa.<br \/>\nTUTTI PICCHIATORI?<\/p>\n<p>&nbsp;<\/p>\n<p><strong>DOPO LA SENTENZA-MENSURATI MARIO BOZZI SENTIERI SI CHIDE GIUSTAMENTE SE SIAMO TUTTI PIACCHIATORI.<\/strong><br \/>\n<strong>Chi ha simpatizzato per il Fronte della Giovent\u00f9 \u00e8 automaticamente un picchiatore.<\/strong><br \/>\n<strong>Sillogismo sconcertante della Cassazione che ha sentenziato contro il giornalista Stefano Mensurati.\u00a0<\/strong><\/p>\n<p>Alzi la mano chi, collocandosi, da giovane,\u00a0 \u201ca destra\u201d, tra\u00a0 i primi Anni Settanta e gli Anni Ottanta del \u2018900, non ha\u00a0 frequentato un nucleo del Fronte della Giovent\u00f9, l\u2019organizzazione giovanile missina dell\u2019epoca.\u00a0 Difficile sfuggire, in tempi\u00a0 di \u00a0 forti radicalizzazioni politiche, al fascino della\u00a0 militanza estrema ed alternativa, insieme comunit\u00e0 e grande famiglia, luogo di elaborazioni eretiche e di impegno politico, di passioni e di illusioni che hanno segnato intere generazioni.\u00a0 Da l\u00ec sono passati centinaia di migliaia di giovani, alcuni dei quali oggi ricoprono alte cariche istituzionali. Da l\u00ec \u00e8 transitata molta dell\u2019attuale classe dirigente, quella delle professioni, dell\u2019Universit\u00e0, dell\u2019informazione.<\/p>\n<p>Bene, ora,\u00a0 secondo una recente sentenza della Cassazione, l\u2019avere appartenuto al FdG porta automaticamente ad essere assimilati alla categoria dei \u201cpicchiatori\u201d.<\/p>\n<p>La Suprema Corte ha infatti assolto un blogger\u00a0che, nel suo sito, aveva definito, nel 2005, l\u2019attuale\u00a0vicedirettore del Gr1Rai, Stefano Mensurati, come \u201cex\u00a0picchiatore fascista\u201d e che, per questo, era stato querelato dal giornalista radiofonico, individuando\u00a0 in un\u2019affermazione autoironica di Mensurati, fatta in un\u2019intervista, pubblicata sul \u201cVenerd\u00ec di Repubblica\u201d,\u00a0 una sorta di ammissione di colpa.<\/p>\n<p>Spiegano\u00a0 i\u00a0 giudici: \u201c\u00e8 stato lo stesso Mensurati in quella intervista ad ammettere di essere stato un simpatizzante, negli anni Settanta, del \u2018Fronte della Giovent\u00f9\u2032, e di \u201daver fatto a botte con i \u2018rossi\u2019, anche se pi\u00f9 che darle le ho prese\u201d.<\/p>\n<p>\u201cAlla luce di questi dati \u2013 scrive la Suprema Corte, nella sentenza 745 \u2013 appare del tutto ingiustificata la richiesta di un intervento punitivo dello Stato, in danno di chi lo ha collocato, nel passato, all\u2019interno di uno schieramento che questo tipo di dialettica della violenza, avente precise radici storiche, non ha mai rinnegato\u201d.<\/p>\n<p>Ad aggravare la posizione del giornalista \u2013 sempre secondo i giudici, che, a questo punto,\u00a0 toccano livelli degni di Torquemada\u00a0 &#8211;\u00a0 le ricordate polemiche che investirono nel 2005 la Rai\u00a0\u201dper aver affidato uno dei \u2018programmi\u00a0di punta\u2019, Radio anch\u2019io, a un giornalista (Mensurati), la cui\u00a0ben precisa posizione politica non corrisponde a quella della\u00a0maggioranza degli italiani e ai principi costituzionali in cui\u00a0essi incondizionatamente credono\u201d.<\/p>\n<p>Il sillogismo \u00e8 perfetto: il FdG era un\u2019orda di picchiatori, Mensurati ha ammesso di essere stato un simpatizzante di questa organizzazione, quindi Mensurati \u00e8 sicuramente un \u201cpicchiatore\u201d. Pi\u00f9 che in un\u2019aula di giustizia sembra di essere in presenza\u00a0 di una rappresentazione del \u201cTeatro dell\u2019assurdo\u201d, sconclusionata e senza senso.<\/p>\n<p>In realt\u00e0 e purtroppo, a volere \u201ccontestualizzare\u201d la vicenda, siamo in presenza\u00a0 di un copione gi\u00e0 visto, che rimanda ad un\u2019epoca, che speravamo tramontata, fatta di discriminazioni, di lutti\u00a0 e di \u201cpicchiatori\u201d veri. Un\u2019epoca, che ci addolora ricordare, ma che per amore di verit\u00e0 non pu\u00f2 essere\u00a0 \u201cletta\u201d rozzamente attraverso una sentenza di parte.<\/p>\n<p>Erano del FdG i martiri di Acca Larenzia (Franco Bigonzetti e Francesco Ciavatta), uccisi, a Roma, nel gennaio 1978,\u00a0 da un commando brigatista,\u00a0 a colpi di\u00a0 mitraglietta. Prima di loro Sergio Ramelli, sprangato premeditatamente\u00a0 da alcuni militanti di Avanguardia Operaia,\u00a0 davanti alla sua abitazione milanese e morto, il 29 aprile 1975, dopo 47 giorni di agonia. Ed ancora prima, il 7 luglio 1972, Carlo Falvella, accoltellato, a Salerno, dall\u2019anarchico Marini. Sono solo alcuni dei nomi di un lungo, drammatico martirologio di giovani del FdG, uccisi, feriti, perseguitati durante\u00a0 quell\u2019autentica guerra civile che ha insanguinato il nostro Paese, \u00a0 tra gli Anni Settanta e gli Anni Ottanta. Tutti picchiatori ? Tutti \u201clupi\u201d di fronte alle pecorelle della sinistra ? Tutti \u201crei\u201d di avere scelto la parte sbagliata ?<\/p>\n<p>Speravamo francamente che quella stagione fosse definitivamente archiviata e consegnata al giudizio della Storia. La sentenza sul caso-Mensurati l\u2019ha purtroppo riproposta, con tutto il suo corollario di interpretazioni faziose e\u00a0 di\u00a0 brucianti discriminazioni, in un giudizio collettivo giuridicamente aberrante, su cui, questo s\u00ec,\u00a0 non rimane che stendere un velo pietoso.<\/p>\n<p><strong>Mario Bozzi Sentieri<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/siamo-tutti-picchiatori-per-la-cassazione-si\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/siamo-tutti-picchiatori-per-la-cassazione-si\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nellla foto il Giudice Paolo Borsellino, fatto saltare in aria dalla Mafia, l&#8217;attuale Sindaco di Roma Gianni Alemanno, il portavoce FLI Granata, partito del Presidente della Camera Fini.Alla Festa Nazionale del Fronte della Giovent\u00f9 del 1990 a Siracusa. TUTTI PICCHIATORI? &nbsp; DOPO LA SENTENZA-MENSURATI MARIO BOZZI SENTIERI SI CHIDE GIUSTAMENTE SE SIAMO TUTTI PIACCHIATORI. Chi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11055,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11054"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11054"}],"version-history":[{"count":11,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11054\/revisions"}],"predecessor-version":[{"id":11067,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11054\/revisions\/11067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11055"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}