{"id":110925,"date":"2017-02-17T15:29:51","date_gmt":"2017-02-17T14:29:51","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=110925"},"modified":"2017-02-17T16:51:48","modified_gmt":"2017-02-17T15:51:48","slug":"trapianto-multiorgani-al-vito-fazzi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/02\/17\/trapianto-multiorgani-al-vito-fazzi\/","title":{"rendered":"PRELIEVO MULTIORGANI AL &#8216;VITO FAZZI&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"224\" title=\"ospedale-vito-fazzi-lecce-300x224\" class=\"alignleft size-full wp-image-110926\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/02\/ospedale-vito-fazzi-lecce-300x224.jpg\" \/>Riceviamo e volentieri pubblichiamo. L&#8217; ufficio stampa dell&#8217; Asl di Lecce ci manda il seguente comunicato______<\/p>\n<p>Cuore, fegato e reni di una donna 53enne donati per offrire un\u2019altra possibilit\u00e0 di vita. Stamattina presto, dopo una lunga notte in sala operatoria, la macchina della donazione del \u201cVito Fazzi\u201d ha portato a termine il suo secondo prelievo multiorgano \u2013 terzo nella ASL Lecce &#8211; dall\u2019inizio dell\u2019anno e, pi\u00f9 precisamente, negli ultimi sette giorni.<\/p>\n<p>I familiari della donatrice salentina, una donna deceduta a causa della gravissima emorragia conseguenza di un aneurisma cerebrale, hanno acconsentito ad avviare la delicata procedura. Che parte con un doloroso e consapevole \u201cs\u00ec\u201d e, dopo una serie di passaggi formali e clinici per valutare l\u2019idoneit\u00e0 di tessuti e organi, mette in gioco capacit\u00e0 e competenze importanti. In questo caso la direzione sanitaria del \u201cFazzi\u201d, diretta dal dott. Giampiero Frassanito, ha fatto fronte alla complessit\u00e0 dell\u2019intervento coinvolgendo medici, infermieri e tecnici di diverse \u00e9quipe medico-chirurgiche. Dal Laboratorio Analisi alla Logistica, passando per la Rianimazione \u2013 il fulcro dell\u2019attivit\u00e0 di donazione e prelievo \u2013 e potendo poi contare sul personale dei reparti di Urologia, Neurologia, Anatomia Patologica e Chirurgia generale, che ha lavorato fianco a fianco con i colleghi arrivati dall\u2019Ospedale \u201cLe Molinette\u201d di Torino e dal Policlinico di Bari. A Torino e Bari, infatti, sono destinati gli organi prelevati a Lecce, punto di partenza di una grande catena di solidariet\u00e0 e anche di efficienza.<\/p>\n<p>Dietro ogni gesto di generosit\u00e0 che proviene dalle famiglie, dietro ogni singola donazione, c\u2019\u00e8 la professionalit\u00e0 dei \u201ccamici bianchi\u201d e l\u2019organizzazione delle strutture ospedaliere, capaci di lavorare in team grazie all\u2019integrazione di uomini e risorse: professionisti di ospedali diversi concentrati sullo stesso prezioso obiettivo. Com\u2019\u00e8 successo soltanto 24 ore prima a Casarano, dove oltre all\u2019impegno del personale del \u201cFerrari\u201d, il lavoro di squadra si \u00e8 arricchito dell\u2019aiuto concreto dei medici dell&#8217;Urologia del \u201cFazzi\u201d, per il prelievo dei reni, e sulla collaborazione del personale di Anatomia Patologica del \u201cFazzi\u201d per la lettura della biopsia effettuata durante il prelievo.<\/p>\n<p>Esempi di buona Sanit\u00e0 e di senso civico, che vanno sostenuti anche con un capillare lavoro di diffusione della cultura della donazione: \u00abAlla base di tutto &#8211; dice il dott. Filippo De Rosa, coordinatore locale per il prelievo e trapianto del \u201cVito Fazzi\u201d \u2013 c\u2019\u00e8 il favorire le donazioni. Un\u2019attivit\u00e0 difficile, lunga e faticosa, perch\u00e9 possiamo avere le migliori professionalit\u00e0 tecniche a disposizione, ma senza la componente umana, la capacit\u00e0 relazionale, l\u2019empatia e il rapporto di fiducia che si riesce ad instaurare con le persone, i familiari, il nostro percorso sarebbe vanificato e non potremmo esprimere loro tutta la nostra gratitudine\u00bb.<\/p>\n<p>Un \u201cprocesso\u201d che in Puglia, in questo breve scorcio del 2017, contabilizza sette donazioni, mentre nel 2016 sono state 51. In Italia, sempre nel 2016, si sono registrate 1596 donazioni, di cui 1303 utilizzate, superando cos\u00ec quota 1300 per la prima volta dal 1992. Un\u2019attivit\u00e0 intensa che ha portato ad effettuare 3736 trapianti, a fronte di 8856 pazienti in lista d\u2019attesa. La loro speranza \u00e8 appesa ad una \u201cchiamata\u201d e, soprattutto, allo scatto di umanit\u00e0 e generosit\u00e0 che altre persone, in qualche altra parte d\u2019Italia, avranno il coraggio di compiere.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/02\/17\/trapianto-multiorgani-al-vito-fazzi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/02\/17\/trapianto-multiorgani-al-vito-fazzi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. L&#8217; ufficio stampa dell&#8217; Asl di Lecce ci manda il seguente comunicato______ Cuore, fegato e reni di una donna 53enne donati per offrire un\u2019altra possibilit\u00e0 di vita. Stamattina presto, dopo una lunga notte in sala operatoria, la macchina della donazione del \u201cVito Fazzi\u201d ha portato a termine il suo secondo prelievo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":110926,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/110925"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=110925"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/110925\/revisions"}],"predecessor-version":[{"id":110930,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/110925\/revisions\/110930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/110926"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=110925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=110925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=110925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}