{"id":11113,"date":"2013-02-15T17:14:57","date_gmt":"2013-02-15T17:14:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11113"},"modified":"2013-02-15T17:15:01","modified_gmt":"2013-02-15T17:15:01","slug":"in-sicurezza-con-una-nuova-rotatoria-la-provinciale-felline-posto-rosso","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/in-sicurezza-con-una-nuova-rotatoria-la-provinciale-felline-posto-rosso\/","title":{"rendered":"IN SICUREZZA CON UNA NUOVA ROTATORIA  LA PROVINCIALE FELLINE-POSTO ROSSO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\">Un altro intervento per mettere in sicurezza un punto critico per la circolazione nel territorio provinciale e per rendere pi\u00f9 agevole il traffico.<\/p>\n<p style=\"text-align: left\">La giunta provinciale, \u00a0ha approvato nell\u2019ultima seduta, il progetto definitivo dei lavori di sistemazione a rotatoria di un incrocio ricadente nel territorio del comune di Alliste.<br \/>\nL\u2019intervento prevede la realizzazione di una <strong>rotatoria sulla intersezione tra la strada provinciale Felline-Posto Rosso con la strada provinciale Felline alla Ugento- Torre San Giovanni<\/strong>.<br \/>\nCon tale intervento \u00e8 prevista la trasformazione dell\u2019attuale incrocio a raso in una rotatoria posta in corrispondenza dell\u2019intersezione tra due strade provinciali ed il raccordo di questa con i prolungamenti delle stesse strade, al fine di migliorare la fruibilit\u00e0 e la sicurezza stradale. Questa modifica, studiata per non interferire con il contesto in cui verr\u00e0 realizzata, avr\u00e0 caratteristiche tali da garantire una maggiore sicurezza per i conducenti ed allo stesso tempo una fluidificazione della circolazione stradale.<\/p>\n<p>\u00a0Questo intervento, che prevede un impegno finanziario di <strong>230 mila euro<\/strong>, rientra nel programma triennale dei Lavori Pubblici 2009-2011 (<em>Manutenzione straordinaria: Interventi di messa in sicurezza di intersezioni lungo le strade provinciali mediante la realizzazione di incroci e realizzazione di rotatorie<\/em>), cofinanziato dalla Regione Puglia nell\u2019ambito del III e IV programma di attuazione del Piano Nazionale della Sicurezza Stradale.<\/p>\n<p>\u201cL\u2019impegno della Provincia prosegue senza sosta per migliorare la rete stradale, ai fini di una migliore percorribilit\u00e0 e sicurezza. Con questo ulteriore intervento, che tende a razionalizzare un incrocio pericoloso, realizzeremo un\u2019opera attesa da tempo dalla comunit\u00e0 di Alliste con l\u2019obiettivo di ottimizzare il livello di fruibilit\u00e0, garantire una maggiore sicurezza stradale e dotare il territorio di collegamenti pi\u00f9 sicuri e di qualit\u00e0\u201d, dichiara l\u2019assessore provinciale ai Lavori Pubblici Massimo Como.La realizzazione della rotatoria risolve un problema molto avvertito dalla comunit\u00e0 di Alliste, in quanto in passato l\u2019incrocio \u00e8 stato teatro di numerosi incidenti automobilistici e riduce la cogestione del traffico veicolare che nel periodo estivo risulta particolarmente intenso, in quanto le strade provinciali interessate conducono a localit\u00e0 marine di grande affollamento.<\/p>\n<p>Soddisfazione a questo proposito viene espressa dal consigliere provinciale e sindaco di Alliste Antonio Renna.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/in-sicurezza-con-una-nuova-rotatoria-la-provinciale-felline-posto-rosso\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/15\/in-sicurezza-con-una-nuova-rotatoria-la-provinciale-felline-posto-rosso\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Un altro intervento per mettere in sicurezza un punto critico per la circolazione nel territorio provinciale e per rendere pi\u00f9 agevole il traffico. La giunta provinciale, \u00a0ha approvato nell\u2019ultima seduta, il progetto definitivo dei lavori di sistemazione a rotatoria di un incrocio ricadente nel territorio del comune di Alliste. L\u2019intervento prevede la realizzazione di una [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11113"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11113"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11113\/revisions"}],"predecessor-version":[{"id":11116,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11113\/revisions\/11116"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}