{"id":11133,"date":"2013-02-16T10:50:40","date_gmt":"2013-02-16T10:50:40","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11133"},"modified":"2013-02-16T10:51:34","modified_gmt":"2013-02-16T10:51:34","slug":"arrestati-due-rapinatori","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/16\/arrestati-due-rapinatori\/","title":{"rendered":"ARRESTATI DUE RAPINATORI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/16\/arrestati-due-rapinatori\/saccheri-franco\/\" rel=\"attachment wp-att-11134\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/SACCHERI-Franco.jpg\" alt=\"\" width=\"1000\" height=\"650\" class=\"alignleft size-full wp-image-11134\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/SACCHERI-Franco.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/SACCHERI-Franco-300x195.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>Nella serata odierna i Carabinieri del Nucleo Radiomobile e della Stazione Lecce Santa Rosa hanno arrestato due rapinatori colti nella flagranza di reato in danno della tabaccheria \u201cPisanello\u201d di questa via Taranto.<\/p>\n<p>Intorno alle ore 19.00 due individui a volto scoperto e armati di pistola irrompevano all\u2019interno della tabaccheria minacciando il titolare, chiedendo l\u2019intero incasso. Coraggiosamente l\u2019esercente reagiva scagliando loro addosso un porta accendini, atteggiamento che metteva in fuga i due malviventi. Senza perdersi d\u2019animo, mentre alcuni testimoni chiamavano il 112, il tabaccaio si poneva all\u2019inseguimento del criminale non armato \u2013 atteso che i due, ad un certo punto della fuga si dividevano \u2013 talch\u00e8 questi, sentitosi braccato non solo perdeva entrambe le scarpe ma inciampava rovinando al suolo. Con mossa repentina il titolare della tabaccheria lo bloccava, essendo per altro il malvivente intontito per una forte contusione alla faccia.<a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/16\/arrestati-due-rapinatori\/sony-dsc-7\/\" rel=\"attachment wp-att-11135\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/15.02.2013-tentata-rapina-via-Taranto-tabacchino.jpg\" alt=\"\" width=\"1000\" height=\"770\" class=\"alignleft size-full wp-image-11135\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/15.02.2013-tentata-rapina-via-Taranto-tabacchino.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/15.02.2013-tentata-rapina-via-Taranto-tabacchino-300x231.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>Nel contempo intervenivano sul posto le pattuglie dell\u2019Arma che, mentre si consumava l\u2019eroico inseguimento appena descritto, grazie all\u2019aiuto di cittadini che avevano visto l\u2019altro complice (armato) scappare in via Scardia, lo intercettavano bloccandolo. Mentre un\u2019altra pattuglia giungeva in ausilio del tabaccaio, lungo la via di fuga i militari del Radiomobile ritrovavano \u2013 occultata dietro un muretto \u2013 una pistola cal. 22 tipo lanciarazzi ed una calzamaglia artigianale, oggetti di cui il rapinatore si era disfatto. Altres\u00ec ritrovavano, sull\u2019altra via di fuga, le scarpe da ginnastica perse dall\u2019altro delinquente. Il tutto veniva sequestrato. Dell\u2019avvenuto arresto \u00e8 stata notiziata la dott.ssa MIGNONE (PM di turno per la Procura di Lecce), che concordava con l\u2019arresto disponendo la traduzione dei due soggetti, identificati in MARZANO Antonio, classe 1984, leccese, pasticcere, sconosciuto alle FF.PP e SACCHERI Franco, leccese, classe 1976, disoccupato, gi\u00e0 noto.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/16\/arrestati-due-rapinatori\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/16\/arrestati-due-rapinatori\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nella serata odierna i Carabinieri del Nucleo Radiomobile e della Stazione Lecce Santa Rosa hanno arrestato due rapinatori colti nella flagranza di reato in danno della tabaccheria \u201cPisanello\u201d di questa via Taranto. Intorno alle ore 19.00 due individui a volto scoperto e armati di pistola irrompevano all\u2019interno della tabaccheria minacciando il titolare, chiedendo l\u2019intero incasso. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11135,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11133"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11133"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11133\/revisions"}],"predecessor-version":[{"id":11139,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11133\/revisions\/11139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11135"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}