{"id":11182,"date":"2013-02-17T08:40:35","date_gmt":"2013-02-17T08:40:35","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=11182"},"modified":"2013-02-17T08:48:47","modified_gmt":"2013-02-17T08:48:47","slug":"il-leccese-antonio-maggio-vince-a-san-remo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/17\/il-leccese-antonio-maggio-vince-a-san-remo\/","title":{"rendered":"IL LECCESE ANTONIO MAGGIO VINCE A SAN REMO"},"content":{"rendered":"<div><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/17\/il-leccese-antonio-maggio-vince-a-san-remo\/maggio\/\" rel=\"attachment wp-att-11185\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/maggio.jpg\" alt=\"\" width=\"300\" height=\"312\" class=\"alignleft size-full wp-image-11185\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/maggio.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/02\/maggio-288x300.jpg 288w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>&#8220;Voglio ringraziare prima di tutto i miei genitori&#8221;: questa la prima frase che ha esclamato il cantante salentino.<\/div>\n<div>a Renzo Rubino,premiato dalla critica, per la caznone sull&#8217;amore omosex \u201cIl postino amami uomo\u201d ; alla canzone\u00a0&#8220;Le parole non servono pi\u00f9&#8221;.<\/div>\n<div>va \u00a0il premio \u00a0per il miglior testo.<\/div>\n<div>Il Presidente della Provincia Gabellone in una nota diffusa alla stampa complimentandosi con il giovane cantante scrive:<\/div>\n<p>&#8220;Talento assoluto, creativit\u00e0, solarit\u00e0 e determinazione. Sono gli ingredienti unici che hanno consentito ad Antonio Maggio di vincere, anzi di stra-vincere, l\u0092edizione 2013 di \u0093SanRemo \u0096 Giovani\u0094.<br \/>\nUna vittoria meritata, il secondo successo di fila di un artista salentino a \u0093SanRemo\u0094, dopo il trionfo di Emma Marrone tra i \u0093big\u0094 nel 2012.<br \/>\nEvidentemente anche la Provincia di Lecce porta\u0085bene!, visto che il giovanissimo Antonio Maggio \u00e8 stato ospite di una beneaugurante e affollata conferenza stampa alla vigilia della partenza per la Liguria; un incontro in cui erano emerse le qualit\u00e0, la semplicit\u00e0 e la determinazione di Antonio, che ha sbaragliato tutti soltanto con il suo mix di umilt\u00e0, convinzione nei propri mezzi e nella bellezza della sua canzone.<br \/>\nIl Salento tutto esulta alla vittoria di Antonio e anzi la Provincia di Lecce aspetta il giovanissimo squinzanese al suo ritorno, finalmente con la statuetta del vincitore!&#8221; .<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/17\/il-leccese-antonio-maggio-vince-a-san-remo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/02\/17\/il-leccese-antonio-maggio-vince-a-san-remo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&#8220;Voglio ringraziare prima di tutto i miei genitori&#8221;: questa la prima frase che ha esclamato il cantante salentino. a Renzo Rubino,premiato dalla critica, per la caznone sull&#8217;amore omosex \u201cIl postino amami uomo\u201d ; alla canzone\u00a0&#8220;Le parole non servono pi\u00f9&#8221;. va \u00a0il premio \u00a0per il miglior testo. Il Presidente della Provincia Gabellone in una nota diffusa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11185,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11182"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=11182"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11182\/revisions"}],"predecessor-version":[{"id":11184,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/11182\/revisions\/11184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/11185"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=11182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=11182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=11182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}