{"id":112023,"date":"2017-03-04T10:07:27","date_gmt":"2017-03-04T09:07:27","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=112023"},"modified":"2017-03-04T10:08:43","modified_gmt":"2017-03-04T09:08:43","slug":"degrado-in-zona-questura","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/04\/degrado-in-zona-questura\/","title":{"rendered":"DEGRADO IN ZONA QUESTURA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"180\" title=\"o\" class=\"alignleft size-medium wp-image-112026\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/o-300x180.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/o-300x180.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/o-768x461.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2017\/03\/o.jpg 790w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Riceviamo e volentieri pubblichiamo. Il presidente dell&#8217; associazione &#8216;Sportello dei diritti&#8217; Giovanni D&#8217; Agata ci scrive______<\/p>\n<p>Non arrivano da Calcutta o da una favela brasiliana le foto che ci ha trasmesso un cittadino. Sono le centralissime vie leccesi Guglielmotto D\u2019Otranto, Nicola Cataldi, Giovanni Camillo Palma, Paolo Emilio Stasi, Luisa Amalia Paladini, tutte adiacenti alla Questura di Lecce che appaiono cos\u00ec: un ricettacolo di rifiuti urbani di ogni specie abbandonati, anche per giorni, sui marciapiedi.<\/p>\n<p>Una situazione che a detta dei residenti si sta perpetuando da mesi e che rende non solo il transito per i pedoni difficoltoso, ma che con il caldo di questi giorni e l\u2019imminente bella stagione, pone un problema di salute pubblica per i miasmi e i pericoli conseguenti alla decomposizione dei rifiuti.<\/p>\n<p>Un problema chE pu\u00f2 essere senz\u2019altro risolto in primo luogo con l\u2019immediata rimozione dell\u2019immondizia gi\u00e0 presente ma che pu\u00f2 essere impedito anche per il futuro con l\u2019intensificazione dei controlli della Polizia Municipale e una maggiore efficienza del servizio di raccolta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/04\/degrado-in-zona-questura\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/03\/04\/degrado-in-zona-questura\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Il presidente dell&#8217; associazione &#8216;Sportello dei diritti&#8217; Giovanni D&#8217; Agata ci scrive______ Non arrivano da Calcutta o da una favela brasiliana le foto che ci ha trasmesso un cittadino. Sono le centralissime vie leccesi Guglielmotto D\u2019Otranto, Nicola Cataldi, Giovanni Camillo Palma, Paolo Emilio Stasi, Luisa Amalia Paladini, tutte adiacenti alla Questura [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":112026,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112023"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=112023"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112023\/revisions"}],"predecessor-version":[{"id":112028,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/112023\/revisions\/112028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/112026"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=112023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=112023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=112023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}